{"id":18169,"date":"2025-05-21T07:00:00","date_gmt":"2025-05-21T05:00:00","guid":{"rendered":"https:\/\/www.meine-tcm.com\/?p=18169"},"modified":"2025-05-21T14:30:29","modified_gmt":"2025-05-21T12:30:29","slug":"quando-la-vicinanza-vi-spaventa-e-desiderate-ancora-una-connessione","status":"publish","type":"post","link":"https:\/\/www.meine-tcm.com\/it\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/","title":{"rendered":"Quando la vicinanza vi spaventa - e desiderate comunque un legame"},"content":{"rendered":"<section class=\"section main-teaser\" id=\"section_1888657619\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-927762684\">\n\n\n\t<div id=\"col-1969091372\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"teaser\">\ud83c\udf3f Avete presente la sensazione che si prova quando un'emozione diventa cos\u00ec forte?,<br \/>che minaccia di sopraffarvi? Quando la rabbia ribolle dentro di voi, la tristezza vi paralizza o le preoccupazioni scorrono come un film senza fine nella vostra testa? Secondo la medicina tradizionale cinese, le emozioni non sono n\u00e9 buone n\u00e9 cattive: sono energie che vogliono fluire attraverso di voi. Se ristagnano, si creano dei blocchi che possono influire sulla salute.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1969091372 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1888657619 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-560186874\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-560186874 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section one-image\" id=\"section_1053663270\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1441705796\">\n\n\n\t<div id=\"col-21210818\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2034724012\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"2160\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug.jpg\" class=\"attachment-original size-original\" alt=\"Tu sei abbastanza. Ora, proprio qui.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug.jpg 2160w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug-12x12.jpg 12w\" sizes=\"auto, (max-width: 2160px) 100vw, 2160px\" title=\"Tu sei abbastanza. Ora, proprio qui.\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2034724012 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p class=\"caption\">Tu sei abbastanza. Ora, proprio qui.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-21210818 > .col-inner {\n  border-radius: 10px;\n  max-width: 640px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1053663270 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-699736726\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-699736726 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section text\" id=\"section_1831689771\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1880778892\">\n\n\n\t<div id=\"col-1735985174\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h2>\ud83c\udf3f Cosa dice la MTC al riguardo:<\/h2>\n<p>Se il cuore (fuoco) \u00e8 troppo aperto e manca la protezione del pericardio, ci sentiamo indifesi.<br \/>Vulnerabile.<br \/>Il nostro Shen trema e perdiamo il contatto con noi stessi.<br \/>Ma c'\u00e8 un modo per sentire la vicinanza senza perdere se stessi.<br \/>Una connessione che rimane delicata e sicura.<\/p>\n<h2>\u2728 3 piccoli rituali che ti proteggono e ti aprono<\/h2>\n<p>Per una vicinanza che faccia stare bene.<br \/>Per una solidariet\u00e0 che pu\u00f2 rimanere.<\/p>\n<h2>\ud83c\udf3f 1. HK 06 - il vostro punto di protezione per il cuore<\/h2>\n<p>Il punto HK 06 (sistema cardiovascolare 6) si trova all'interno dell'avambraccio, circa due dita sopra la piega del polso. Appoggiarvi delicatamente il pollice.<br \/>Inspirate e, mentre espirate, immaginate come una calda copertura protettiva avvolga il vostro cuore.<\/p>\n<p>Questo punto \u00e8 come un cancello: protegge il cuore, ma non lo chiude a chiave.<br \/><strong>\ud83d\udc47 Qui vi mostrer\u00f2 come trovare il punto:<\/strong><br \/><a href=\"https:\/\/www.meine-tcm.com\/it\/punti-di-agopuntura\/punto-di-agopuntura-hk-06\/\" target=\"_blank\" rel=\"noopener\">www.meine-tcm.com\/akupunkturpunkte\/akupunkturpunkt-hk-06<\/a><\/p>\n<h2>\ud83c\udf38 2\u00b0 esercizio di Qi Gong \u201eCondividere le nuvole\u201c - creare spazio, aprire il cuore<\/h2>\n<p>State dritti, con i piedi ben radicati.<br \/>Muovete delicatamente entrambe le mani verso l'alto come se steste tenendo una nuvola.<br \/>Poi apriteli lentamente a destra e a sinistra, come se steste diradando le nuvole per far passare la luce.<br \/>Questo movimento crea spazio intorno a voi.<br \/>Spazio per voi.<br \/>Spazio di connessione.<\/p>\n<p>\u00a0\ud83d\udc47 Qui vi mostrer\u00f2 come eseguire questo esercizio:<br \/><a href=\"https:\/\/www.meine-tcm.com\/it\/condividere-le-nuvole\/\" target=\"_blank\" rel=\"noopener\">www.meine-tcm.com\/wolken-teilen<\/a><\/p>\n<h2>\ud83c\udf31 3a meditazione guidata: \u201eTutto pu\u00f2 essere come \u00e8\u201c.\u201c<\/h2>\n<p>Mettetevi comodi.<br \/>Inspirare profondamente... ed espirare.<br \/>Questa meditazione invita a essere semplicemente, con tutto ci\u00f2 che c'\u00e8 in questo momento.<br \/>Il desiderio. L'inquietudine. La speranza.<br \/>Nulla deve essere diverso.<br \/>Ed \u00e8 proprio l\u00ec, in questo permettere, che sorge la pace.<\/p>\n<p>Quando non dovete pi\u00f9 respingere nulla, diventa pi\u00f9 facile sentirsi in connessione con voi stessi e con gli altri.<\/p>\n<p>\ud83d\udc47 Cliccate qui per la meditazione:<br \/><a href=\"https:\/\/www.youtube.com\/watch?v=crfaWHTxkD0&amp;t=181s\" target=\"_blank\" rel=\"noopener\">www.youtube.com\/watch?v=crfaWHTxkD0&amp;t=181s<\/a><\/p>\n<p><strong>Volete sapere cosa sta rafforzando il vostro cuore in questo momento?<\/strong><br \/>Fate la nostra analisi gratuita della MTC e scoprite quale elemento vi sta sostenendo in questo momento.<br \/>\ud83d\udc49 Cliccare qui per l'analisi TCM: <a href=\"https:\/\/www.meine-tcm.com\/it\/analisi-tcm\/\" target=\"_blank\" rel=\"noopener\">www.meine-tcm.com\/tcm-analyse<\/a><\/p>\n<h2>\ud83c\udf3f Conclusione<\/h2>\n<p>La vera vicinanza non nasce quando ci si deve proteggere, ma quando ci si permette di essere. Proprio cos\u00ec. Ora. Qui.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1735985174 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1831689771 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1525012877\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1525012877 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section quote\" id=\"section_112048286\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-425785151\">\n\n\n\t<div id=\"col-878984548\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p>La vera vicinanza inizia quando si riesce a trattenersi.<\/p>\n<p class=\"quote-from\">Autore: Sconosciuto<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-878984548 > .col-inner {\n  max-width: 600px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_112048286 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(255, 244, 217);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-994024834\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-994024834 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section h2\" id=\"section_2092586354\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-219804884\">\n\n\n\t<div id=\"col-810151850\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Altri suggerimenti e articoli interessanti<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-810151850 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2092586354 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section blogposts-overview\" id=\"section_669172221\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-848021305\">\n\n\n\t<div id=\"col-1280482490\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n  <style>\n    #row-2056221802 .grid-col-1{height: 600px}\n    #row-2056221802 .grid-col-1-2{height: 300px}\n    #row-2056221802 .grid-col-1-3{height:200px}\n    #row-2056221802 .grid-col-2-3{height: 400px}\n    #row-2056221802 .grid-col-1-4{height: 150px}\n    #row-2056221802 .grid-col-3-4{height: 450px}\n\n\n        \/* Tablet *\/\n    @media (max-width: 850px){\n      #row-2056221802 .grid-col-1{height: 400px}\n      #row-2056221802 .grid-col-1-2{height: 200px}\n      #row-2056221802 .grid-col-1-3{height:133.33333333333px}\n      #row-2056221802 .grid-col-2-3{height: 266.66666666667px}\n      #row-2056221802 .grid-col-1-4{height: 100px}\n      #row-2056221802 .grid-col-3-4{height: 300px}\n    }\n    \n        \/* Mobile *\/\n    @media (max-width: 550px){\n      #row-2056221802 .grid-col-1{height: 400px}\n      #row-2056221802 .grid-col-1-2{height: 200px}\n      #row-2056221802 .grid-col-1-3{height:133.33333333333px}\n      #row-2056221802 .grid-col-2-3{height: 266.66666666667px}\n      #row-2056221802 .grid-col-1-4{height: 100px}\n      #row-2056221802 .grid-col-3-4{height: 300px}\n    }\n    \n\n  <\/style>\n  \n  \n    <div id=\"row-2056221802\" class=\"row row-small row-full-width row-grid\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"col post-item grid-col grid-col-1 large-6 medium-12\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/die-herz-zeit-nutzen\/\" class=\"plain\" aria-label=\"Die Herz\u2013Zeit nutzen\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/die-herz-zeit-nutzen\/\" class=\"plain\">Die Herz\u2013Zeit nutzen<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t11:47 Uhr. Du sitzt am Schreibtisch. Die Mails stapeln sich. Das Meeting vorhin war anstrengend. Du greifst zum dritten Kaffee. Oder:\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">14<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Capocorda<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wenn-hitze-krank-macht\/\" class=\"plain\" aria-label=\"Quando il caldo fa ammalare\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Il sole d\u00e0 la vita. Ma pu\u00f2 anche toglierla, se non ti proteggi.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Il sole d\u00e0 la vita. Ma pu\u00f2 anche toglierla, se non ti proteggi.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wenn-hitze-krank-macht\/\" class=\"plain\">Quando il caldo fa ammalare<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\tNon inizia all\u2019improvviso. Inizia in modo impercettibile. A poco a poco. Quasi non te ne accorgi. All\u2019inizio sei solo stanco. Poi ti senti appesantito. Poi arriva\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">07<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Capocorda<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\" aria-label=\"Perch\u00e9 la pancia si ribella in estate\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Il cuore sa ci\u00f2 che la mente non riesce a esprimere. Ascoltalo.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Il cuore sa ci\u00f2 che la mente non riesce a esprimere. Ascoltalo.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\">Perch\u00e9 la pancia si ribella in estate<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\" aria-label=\"Perch\u00e9 l&#039;estate mette a dura prova la circolazione \u2014 e cosa consiglia la MTC per ovviare a questo problema\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Q\u00ed B\u00f3 | L&#039;imperatore giallo Huangdi | Dr. Weber\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Servizio fotografico \u201cChiedi all\u2019Imperatore Giallo\u201d (BTS) \u2013 luglio 2026\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tSpiegazione della MTC in generale \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\">Perch\u00e9 l'estate mette a dura prova la circolazione \u2014 e cosa consiglia la MTC per ovviare a questo problema<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">26<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\" aria-label=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tAlimentazione MTC Consiglio della settimana \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\">La bevanda estiva Yin \u2014 il segreto degli antichi maestri<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">26<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/schlafprobleme-im-sommer\/\" class=\"plain\" aria-label=\"Problemi di sonno in estate\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Non \u00e8 il caldo a privarti del sonno. \u00c8 uno spirito che non pu\u00f2 trovare pace.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Non \u00e8 il caldo a privarti del sonno. \u00c8 uno spirito che non pu\u00f2 trovare pace.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/schlafprobleme-im-sommer\/\" class=\"plain\">Problemi di sonno in estate<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">23<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\" aria-label=\"Perch\u00e9 in estate sei pi\u00f9 irritabile \u2014 il \u201cfuoco del fegato\u201d nella MTC\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Tu non sei cos\u00ec. Ma in questo momento ti senti estraneo a te stesso.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Tu non sei cos\u00ec. Ma in questo momento ti senti estraneo a te stesso.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\">Perch\u00e9 in estate sei pi\u00f9 irritabile \u2014 il \u201cfuoco del fegato\u201d nella MTC<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item has-post-icon grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\" aria-label=\"RITIRO: Qi Gong e respirazione TAO (marzo 2027)\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Retiro di qigong in primavera in Tirolo - Anteprima\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t\t\t<div class=\"absolute no-click x50 y50 md-x50 md-y50 lg-x50 lg-y50\">\n  \t\t\t\t            \t<div class=\"overlay-icon\">\n  \t\t\t\t                    <i class=\"icon-play\" aria-hidden=\"true\"><\/i>  \t\t\t\t                <\/div>\n  \t\t\t\t            <\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tRitiri \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\">RITIRO: Qi Gong e respirazione TAO (marzo 2027)<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">10<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1280482490 > .col-inner {\n  max-width: 1060px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_669172221 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-632260531\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-632260531 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section h2\" id=\"section_122649237\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-31600068\">\n\n\n\t<div id=\"col-1294438457\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>I nostri prodotti pi\u00f9 popolari<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1294438457 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_122649237 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1499147855\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1499147855 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section top-produkte\" id=\"section_288242577\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-163478499\">\n\n\n\t<div id=\"col-523172956\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t\n  \n    <div class=\"row  equalize-box large-columns-5 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" aria-label=\"Corso di Qi Gong per principianti e studenti leggermente avanzati\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-fuer-anfaenger-06-online-ansehen-mobile-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corso di Qi Gong per principianti da Einfach besser leben Online\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Gong per principianti con Wolfgang nell&#039;immagine\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Corso di Qi Gong per principianti da Einfach besser leben\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1368\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Corso di Qi Gong per principianti e studenti leggermente avanzati<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1368\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" aria-label=\"AkuPen - l&#039;ingegnosa penna per agopuntura con istruzioni video\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-weiss-vertikal-3-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"AkuPen aperto\" aria-hidden=\"true\" title=\"AkuPen da Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"AukPen con confezione in legno\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled-800x1131.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1087x1536.jpg 1087w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1449x2048.jpg 1449w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-8x12.jpg 8w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled.jpg 1811w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"AkuPen con istruzioni video\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1365\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tAkuPen\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">AkuPen - l'ingegnosa penna per agopuntura con istruzioni video<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>80,57&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1365\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" aria-label=\"Corso di Qi Gong II - Le 18 figure dell&#039;armonia\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-05-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corsi video online di Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Qong moderno - Le 18 figure dell&#039;armonia\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Corso di Qi Qong - Le 18 figure dell&#039;armonia\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1376\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Corso di Qi Gong II - Le 18 figure dell'armonia<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>35,19&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1376\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-8-brokate\/\" aria-label=\"Le 8 brocche - Il corso di Qi Gong moderno I\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/qi-gong-kurs-8-brokate-07-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corsi video online di Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Gong moderno 8 broccati con Wolfgang\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-800x1130.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-600x847.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i.jpg 1062w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Il corso moderno di Qi Gong 8 Broccato di una vita semplicemente migliore\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1416\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-8-brokate\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Le 8 brocche - Il corso di Qi Gong moderno I<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1416\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/weidinger-w08-warme-mitte\/\" aria-label=\"Weidinger W08 - Centro caldo\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-1-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" aria-hidden=\"true\" title=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" \/><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1295\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tWeidinger\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/weidinger-w08-warme-mitte\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Weidinger W08 - Centro caldo<\/a><\/p><p class=\"woocommerce-loop-product__subtitle wp-subtitle\">Miscela di erbe della MTC<\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>62,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1295\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-523172956 > .col-inner {\n  max-width: 1200px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_288242577 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n<style>\nh2 {\ntext-align: left;\n}\n\nsection.one-image .img {\nmargin-bottom: 0 !important;\n}\n\nsection.one-image img {\n    border-radius: 15px;\n}\n<\/style>\n\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Ci sono momenti in cui non si desidera altro che sentirsi connessi.<br \/>\nCon un essere umano.<br \/>\nCon il mondo.<br \/>\nCon se stessi.<br \/>\nEppure...<br \/>\nNon appena qualcuno si avvicina, qualcosa dentro di voi si ritira.<br \/>\nCome una conchiglia che si chiude prima di essere ferita.<\/p>","protected":false},"author":3859,"featured_media":18170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[300],"tags":[],"class_list":["post-18169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tcm-tipp-der-woche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bindungsangst \u00fcberwinden: 3 TCM-Praktiken<\/title>\n<meta name=\"description\" content=\"Sehns\u00fcchtig nach N\u00e4he, aber \u00e4ngstlich vor Verletzung? Entdecke 3 TCM\u2013\u00dcbungen, die dein Herz sch\u00fctzen und zugleich f\u00fcr Verbindung \u00f6ffnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meine-tcm.com\/it\/quando-la-vicinanza-vi-spaventa-e-desiderate-ancora-una-connessione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bindungsangst \u00fcberwinden: 3 TCM-Praktiken\" \/>\n<meta property=\"og:description\" content=\"Sehns\u00fcchtig nach N\u00e4he, aber \u00e4ngstlich vor Verletzung? Entdecke 3 TCM\u2013\u00dcbungen, die dein Herz sch\u00fctzen und zugleich f\u00fcr Verbindung \u00f6ffnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meine-tcm.com\/it\/quando-la-vicinanza-vi-spaventa-e-desiderate-ancora-una-connessione\/\" \/>\n<meta property=\"og:site_name\" content=\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-21T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T12:30:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"2160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/\"},\"author\":{\"name\":\"Marina\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/76da350caed5aad1d9998ba607d86f28\"},\"headline\":\"Wenn N\u00e4he Angst macht \u2014 und du dich trotzdem nach Verbundenheit sehnst\",\"datePublished\":\"2025-05-21T05:00:00+00:00\",\"dateModified\":\"2025-05-21T12:30:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/\"},\"wordCount\":751,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/du-bist-genug.jpg\",\"articleSection\":[\"TCM Tipp der Woche\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/\",\"name\":\"Bindungsangst \u00fcberwinden: 3 TCM-Praktiken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/du-bist-genug.jpg\",\"datePublished\":\"2025-05-21T05:00:00+00:00\",\"dateModified\":\"2025-05-21T12:30:29+00:00\",\"description\":\"Sehns\u00fcchtig nach N\u00e4he, aber \u00e4ngstlich vor Verletzung? Entdecke 3 TCM\u2013\u00dcbungen, die dein Herz sch\u00fctzen und zugleich f\u00fcr Verbindung \u00f6ffnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/du-bist-genug.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/du-bist-genug.jpg\",\"width\":2160,\"height\":2160,\"caption\":\"Du bist genug. Jetzt. genau hier.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meine-tcm.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wenn N\u00e4he Angst macht \u2014 und du dich trotzdem nach Verbundenheit sehnst\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"name\":\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\",\"description\":\"Einfach gesund bleiben\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meine-tcm.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\",\"name\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"width\":559,\"height\":479,\"caption\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/meinetcm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EinfachbesserLeben\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/76da350caed5aad1d9998ba607d86f28\",\"name\":\"Marina\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Superare la paura di impegnarsi: 3 pratiche di MTC","description":"Desiderate la vicinanza ma avete paura di essere feriti? Scoprite 3 esercizi di MTC che proteggono il vostro cuore e allo stesso tempo vi aprono alla connessione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meine-tcm.com\/it\/quando-la-vicinanza-vi-spaventa-e-desiderate-ancora-una-connessione\/","og_locale":"it_IT","og_type":"article","og_title":"Bindungsangst \u00fcberwinden: 3 TCM-Praktiken","og_description":"Sehns\u00fcchtig nach N\u00e4he, aber \u00e4ngstlich vor Verletzung? Entdecke 3 TCM\u2013\u00dcbungen, die dein Herz sch\u00fctzen und zugleich f\u00fcr Verbindung \u00f6ffnen.","og_url":"https:\/\/www.meine-tcm.com\/it\/quando-la-vicinanza-vi-spaventa-e-desiderate-ancora-una-connessione\/","og_site_name":"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt","article_published_time":"2025-05-21T05:00:00+00:00","article_modified_time":"2025-05-21T12:30:29+00:00","og_image":[{"width":2160,"height":2160,"url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug.jpg","type":"image\/jpeg"}],"author":"Marina","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Marina","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/#article","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/"},"author":{"name":"Marina","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/76da350caed5aad1d9998ba607d86f28"},"headline":"Wenn N\u00e4he Angst macht \u2014 und du dich trotzdem nach Verbundenheit sehnst","datePublished":"2025-05-21T05:00:00+00:00","dateModified":"2025-05-21T12:30:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/"},"wordCount":751,"commentCount":0,"publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"image":{"@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug.jpg","articleSection":["TCM Tipp der Woche"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/","url":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/","name":"Superare la paura di impegnarsi: 3 pratiche di MTC","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/#primaryimage"},"image":{"@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug.jpg","datePublished":"2025-05-21T05:00:00+00:00","dateModified":"2025-05-21T12:30:29+00:00","description":"Desiderate la vicinanza ma avete paura di essere feriti? Scoprite 3 esercizi di MTC che proteggono il vostro cuore e allo stesso tempo vi aprono alla connessione.","breadcrumb":{"@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/#primaryimage","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug.jpg","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/du-bist-genug.jpg","width":2160,"height":2160,"caption":"Du bist genug. Jetzt. genau hier."},{"@type":"BreadcrumbList","@id":"https:\/\/www.meine-tcm.com\/wenn-naehe-angst-macht-und-du-dich-trotzdem-nach-verbundenheit-sehnst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meine-tcm.com\/"},{"@type":"ListItem","position":2,"name":"Wenn N\u00e4he Angst macht \u2014 und du dich trotzdem nach Verbundenheit sehnst"}]},{"@type":"WebSite","@id":"https:\/\/www.meine-tcm.com\/#website","url":"https:\/\/www.meine-tcm.com\/","name":"la mia MTC | Medicina Tradizionale Cinese spiegata in modo semplice","description":"Rimanere semplicemente in salute","publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meine-tcm.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.meine-tcm.com\/#organization","name":"meine-TCM.com - La Medicina Tradizionale Cinese spiegata in modo semplice","url":"https:\/\/www.meine-tcm.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","width":559,"height":479,"caption":"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt"},"image":{"@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/meinetcm\/","https:\/\/www.youtube.com\/@EinfachbesserLeben"]},{"@type":"Person","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/76da350caed5aad1d9998ba607d86f28","name":"Marina"}]}},"wps_subtitle":"TCM\u2013Rituale f\u00fcr dein Herz, wenn N\u00e4he beides ist: Sehnsucht und Furcht","_links":{"self":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts\/18169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/users\/3859"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/comments?post=18169"}],"version-history":[{"count":0,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts\/18169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/media\/18170"}],"wp:attachment":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/media?parent=18169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/categories?post=18169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/tags?post=18169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}