{"id":17595,"date":"2025-03-26T06:30:00","date_gmt":"2025-03-26T05:30:00","guid":{"rendered":"https:\/\/www.meine-tcm.com\/?p=17595"},"modified":"2025-02-28T16:27:10","modified_gmt":"2025-02-28T15:27:10","slug":"dallinquietudine-alla-forza-interiore-il-percorso-tcm-verso-la-serenita","status":"publish","type":"post","link":"https:\/\/www.meine-tcm.com\/it\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/","title":{"rendered":"Dall'inquietudine alla forza interiore: il percorso della MTC verso la serenit\u00e0"},"content":{"rendered":"<section class=\"section main-teaser\" id=\"section_975812889\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1927199516\">\n\n\n\t<div id=\"col-766798088\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"teaser\">Sentite questa UNRUHE interiore che non vuole saperne di smettere?<br \/>I vostri pensieri saltano da un argomento all'altro.<br \/>Il corpo \u00e8 teso.<br \/>Si vorrebbe solo spegnere, ma non ci si riesce.<br \/>Forse questa inquietudine \u00e8 sgradevole. Ma se<br \/>vuole dirti qualcosa?<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-766798088 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_975812889 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-64117545\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-64117545 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section one-image\" id=\"section_458198242\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1935674472\">\n\n\n\t<div id=\"col-1121267897\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1784241182\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"2160\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element.jpg\" class=\"attachment-original size-original\" alt=\"L&#039;inquietudine scompare quando si d\u00e0 spazio al silenzio.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element.jpg 2160w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element-12x12.jpg 12w\" sizes=\"auto, (max-width: 2160px) 100vw, 2160px\" title=\"L&#039;inquietudine scompare quando si d\u00e0 spazio al silenzio.\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1784241182 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p class=\"caption\">L'inquietudine scompare quando si d\u00e0 spazio al silenzio.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1121267897 > .col-inner {\n  border-radius: 10px;\n  max-width: 640px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_458198242 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1056197301\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1056197301 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section text\" id=\"section_1701719183\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-477578142\">\n\n\n\t<div id=\"col-611282467\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h2>\ud83c\udf3e Irrequietezza - l'energia inquieta dell'elemento legno<\/h2>\n<p>Nella Medicina Tradizionale Cinese (MTC), l'irrequietezza fa parte dell'elemento legno, l'energia della crescita, del cambiamento e del movimento. Ci spinge ad andare avanti, ci permette di progredire.<\/p>\n<p>Ma se questa energia non pu\u00f2 fluire, si accumula.<br \/>I pensieri girano all'infinito. Il corpo si sente teso. Si ha la sensazione di essere guidati.<\/p>\n<p>Molte persone sperimentano un nervosismo interiore durante questo periodo, come se qualcosa dentro di loro stesse spingendo in avanti senza fare progressi.<\/p>\n<p>Tuttavia, questo non \u00e8 un segno di debolezza, ma un segno che il Qi vuole ricominciare a fluire.<\/p>\n<p>La soluzione? Non lottare contro l'agitazione, ma darle una direzione.<\/p>\n<h2>\u2728 3 modi per trasformare dolcemente l'inquietudine in calma:<\/h2>\n<p><strong>1\ufe0f\u20e3 Picchiettamento dei meridiani: un rapido sollievo per il corpo<\/strong><br \/>Se vi sentite irrequieti, un leggero picchiettamento dei meridiani pu\u00f2 aiutarvi a riequilibrare immediatamente l'energia.<\/p>\n<p>\ud83d\udca1 <strong>Suggerimento:<\/strong> Picchiettare delicatamente il punto 3 del fegato (Tai Chong)<br \/>\ud83d\udccd Si trova sul dorso del piede, tra il primo e il secondo dito.<br \/>\u27a1\ufe0f Picchiettate o massaggiate delicatamente per 30 secondi: sentite come si scioglie la tensione interiore.<\/p>\n<p>\ud83d\udc49 <strong>Per saperne di pi\u00f9 sul fegato 3:<br \/><\/strong><a href=\"https:\/\/www.meine-tcm.com\/it\/punti-di-agopuntura\/punto-di-agopuntura-le-03\/\" target=\"_blank\" rel=\"noopener\">www.meine-tcm.com\/akupunkturpunkte\/akupunkturpunkt-le-03<\/a><\/p>\n<p>Perch\u00e9 \u00e8 utile?<br \/>\ud83d\udc49 Il punto 3 del fegato \u00e8 IL punto per rilasciare il Qi stagnante - perfetto per quando <strong>Irrequietezza e nervosismo<\/strong> si sono accumulati.<\/p>\n<p><strong>2\ufe0f\u20e3 La visualizzazione dell'albero: la pace attraverso il radicamento<\/strong><br \/>L'irrequietezza nasce spesso quando non ci sentiamo a terra. Questa breve visualizzazione dell'albero vi d\u00e0 stabilit\u00e0.<\/p>\n<p><strong>\ud83d\udca1 Suggerimento: chiudete gli occhi e immaginate:<\/strong><br \/>\ud83c\udf3f Siete un albero. Le tue radici crescono in profondit\u00e0 nella terra.<br \/>\ud83d\udca8 Il vento muove i vostri rami, ma il vostro tronco rimane saldo.<br \/>Ad ogni respiro ci si sente pi\u00f9 calmi, pi\u00f9 stabili e pi\u00f9 rilassati.<\/p>\n<p>Perch\u00e9 \u00e8 utile?<br \/>Questo esercizio d\u00e0 immediatamente una sensazione di radicamento, perfetta per i momenti in cui la testa \u00e8 troppo piena.<\/p>\n<p><strong>3\ufe0f\u20e3 Canticchiare per la serenit\u00e0 interiore - Respirazione delle api<br \/><\/strong>Sapevate che un semplice suono pu\u00f2 calmare il vostro tumulto interiore? La respirazione delle api (Bhramari) aiuta a rilassare il sistema nervoso in pochi minuti.<\/p>\n<p>\ud83d\udca1<strong> Suggerimento: ecco come funziona:<\/strong><br \/>\u27a1\ufe0f Respirate profondamente.<br \/>\u27a1\ufe0f Quando espirate, canticchiate a bocca chiusa, come un'ape.<br \/>\u27a1\ufe0f Sentite la vibrazione delicata nel vostro corpo.<\/p>\n<p>Perch\u00e9 \u00e8 utile?<br \/>\ud83d\udc49 Canticchiare attiva il nervo vago, rallenta il battito cardiaco e rilassa immediatamente.<\/p>\n<h2>\ud83c\udf3f Il vostro consiglio della MTC: date una direzione all'irrequietezza<\/h2>\n<p>L'irrequietezza non \u00e8 un nemico, ma un'energia che vuole fluire.<br \/>Attraverso il movimento, il radicamento a terra e suoni delicati, \u00e8 possibile trasformarli in calma.<\/p>\n<p>Scoprite come far fluire di nuovo il vostro Qi!<br \/>\ud83d\udd0e Prendete il questionario gratuito della MTC e scoprite di cosa ha bisogno il vostro corpo in questo momento: <a href=\"https:\/\/www.meine-tcm.com\/it\/questionario\/\" target=\"_blank\" rel=\"noopener\">www.meine-tcm.com\/fragebogen<\/a><\/p>\n<h2>Conclusione:<\/h2>\n<p>L'irrequietezza non rimane per sempre. Sta solo aspettando che la trasformiate delicatamente in calma.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-611282467 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1701719183 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1131509140\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1131509140 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section quote\" id=\"section_1675195102\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-580845937\">\n\n\n\t<div id=\"col-1539416306\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p>Il vento pu\u00f2 infuriare, ma le radici restano forti.<\/p>\n<p class=\"quote-from\">Autore: Sconosciuto<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1539416306 > .col-inner {\n  max-width: 600px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1675195102 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(255, 244, 217);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1087328700\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1087328700 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section h2\" id=\"section_1260650903\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1766499551\">\n\n\n\t<div id=\"col-889312421\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Altri suggerimenti e articoli interessanti<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-889312421 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1260650903 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section blogposts-overview\" id=\"section_2135828779\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-999673540\">\n\n\n\t<div id=\"col-661005630\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n  <style>\n    #row-1316141307 .grid-col-1{height: 600px}\n    #row-1316141307 .grid-col-1-2{height: 300px}\n    #row-1316141307 .grid-col-1-3{height:200px}\n    #row-1316141307 .grid-col-2-3{height: 400px}\n    #row-1316141307 .grid-col-1-4{height: 150px}\n    #row-1316141307 .grid-col-3-4{height: 450px}\n\n\n        \/* Tablet *\/\n    @media (max-width: 850px){\n      #row-1316141307 .grid-col-1{height: 400px}\n      #row-1316141307 .grid-col-1-2{height: 200px}\n      #row-1316141307 .grid-col-1-3{height:133.33333333333px}\n      #row-1316141307 .grid-col-2-3{height: 266.66666666667px}\n      #row-1316141307 .grid-col-1-4{height: 100px}\n      #row-1316141307 .grid-col-3-4{height: 300px}\n    }\n    \n        \/* Mobile *\/\n    @media (max-width: 550px){\n      #row-1316141307 .grid-col-1{height: 400px}\n      #row-1316141307 .grid-col-1-2{height: 200px}\n      #row-1316141307 .grid-col-1-3{height:133.33333333333px}\n      #row-1316141307 .grid-col-2-3{height: 266.66666666667px}\n      #row-1316141307 .grid-col-1-4{height: 100px}\n      #row-1316141307 .grid-col-3-4{height: 300px}\n    }\n    \n\n  <\/style>\n  \n  \n    <div id=\"row-1316141307\" class=\"row row-small row-full-width row-grid\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"col post-item grid-col grid-col-1 large-6 medium-12\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/die-herz-zeit-nutzen\/\" class=\"plain\" aria-label=\"Die Herz\u2013Zeit nutzen\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/die-herz-zeit-nutzen\/\" class=\"plain\">Die Herz\u2013Zeit nutzen<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t11:47 Uhr. Du sitzt am Schreibtisch. Die Mails stapeln sich. Das Meeting vorhin war anstrengend. Du greifst zum dritten Kaffee. Oder:\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">14<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Capocorda<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wenn-hitze-krank-macht\/\" class=\"plain\" aria-label=\"Quando il caldo fa ammalare\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Il sole d\u00e0 la vita. Ma pu\u00f2 anche toglierla, se non ti proteggi.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Il sole d\u00e0 la vita. Ma pu\u00f2 anche toglierla, se non ti proteggi.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wenn-hitze-krank-macht\/\" class=\"plain\">Quando il caldo fa ammalare<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\tNon inizia all\u2019improvviso. Inizia in modo impercettibile. A poco a poco. Quasi non te ne accorgi. All\u2019inizio sei solo stanco. Poi ti senti appesantito. Poi arriva\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">07<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Capocorda<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\" aria-label=\"Perch\u00e9 la pancia si ribella in estate\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Il cuore sa ci\u00f2 che la mente non riesce a esprimere. Ascoltalo.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Il cuore sa ci\u00f2 che la mente non riesce a esprimere. Ascoltalo.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\">Perch\u00e9 la pancia si ribella in estate<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\" aria-label=\"Perch\u00e9 l&#039;estate mette a dura prova la circolazione \u2014 e cosa consiglia la MTC per ovviare a questo problema\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Q\u00ed B\u00f3 | L&#039;imperatore giallo Huangdi | Dr. Weber\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Servizio fotografico \u201cChiedi all\u2019Imperatore Giallo\u201d (BTS) \u2013 luglio 2026\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tSpiegazione della MTC in generale \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\">Perch\u00e9 l'estate mette a dura prova la circolazione \u2014 e cosa consiglia la MTC per ovviare a questo problema<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">26<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\" aria-label=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tAlimentazione MTC Consiglio della settimana \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\">La bevanda estiva Yin \u2014 il segreto degli antichi maestri<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">26<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/schlafprobleme-im-sommer\/\" class=\"plain\" aria-label=\"Problemi di sonno in estate\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Non \u00e8 il caldo a privarti del sonno. \u00c8 uno spirito che non pu\u00f2 trovare pace.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Non \u00e8 il caldo a privarti del sonno. \u00c8 uno spirito che non pu\u00f2 trovare pace.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/schlafprobleme-im-sommer\/\" class=\"plain\">Problemi di sonno in estate<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">23<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\" aria-label=\"Perch\u00e9 in estate sei pi\u00f9 irritabile \u2014 il \u201cfuoco del fegato\u201d nella MTC\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Tu non sei cos\u00ec. Ma in questo momento ti senti estraneo a te stesso.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Tu non sei cos\u00ec. Ma in questo momento ti senti estraneo a te stesso.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tIl consiglio della settimana della MTC \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\">Perch\u00e9 in estate sei pi\u00f9 irritabile \u2014 il \u201cfuoco del fegato\u201d nella MTC<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item has-post-icon grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\" aria-label=\"RITIRO: Qi Gong e respirazione TAO (marzo 2027)\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Retiro di qigong in primavera in Tirolo - Anteprima\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t\t\t<div class=\"absolute no-click x50 y50 md-x50 md-y50 lg-x50 lg-y50\">\n  \t\t\t\t            \t<div class=\"overlay-icon\">\n  \t\t\t\t                    <i class=\"icon-play\" aria-hidden=\"true\"><\/i>  \t\t\t\t                <\/div>\n  \t\t\t\t            <\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tRitiri \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\">RITIRO: Qi Gong e respirazione TAO (marzo 2027)<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">10<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Giu<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-661005630 > .col-inner {\n  max-width: 1060px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2135828779 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1511373334\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1511373334 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section h2\" id=\"section_1277488587\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1383207577\">\n\n\n\t<div id=\"col-1228179733\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>I nostri prodotti pi\u00f9 popolari<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1228179733 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1277488587 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1278867710\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1278867710 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section top-produkte\" id=\"section_1538159648\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1313087371\">\n\n\n\t<div id=\"col-3901745\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t\n  \n    <div class=\"row  equalize-box large-columns-5 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" aria-label=\"Corso di Qi Gong per principianti e studenti leggermente avanzati\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-fuer-anfaenger-06-online-ansehen-mobile-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corso di Qi Gong per principianti da Einfach besser leben Online\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Gong per principianti con Wolfgang nell&#039;immagine\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Corso di Qi Gong per principianti da Einfach besser leben\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1368\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Corso di Qi Gong per principianti e studenti leggermente avanzati<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1368\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" aria-label=\"AkuPen - l&#039;ingegnosa penna per agopuntura con istruzioni video\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-weiss-vertikal-3-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"AkuPen aperto\" aria-hidden=\"true\" title=\"AkuPen da Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"AukPen con confezione in legno\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled-800x1131.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1087x1536.jpg 1087w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1449x2048.jpg 1449w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-8x12.jpg 8w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled.jpg 1811w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"AkuPen con istruzioni video\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1365\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tAkuPen\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">AkuPen - l'ingegnosa penna per agopuntura con istruzioni video<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>80,57&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1365\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" aria-label=\"Corso di Qi Gong II - Le 18 figure dell&#039;armonia\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-05-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corsi video online di Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Qong moderno - Le 18 figure dell&#039;armonia\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Corso di Qi Qong - Le 18 figure dell&#039;armonia\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1376\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Corso di Qi Gong II - Le 18 figure dell'armonia<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>35,19&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1376\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-8-brokate\/\" aria-label=\"Le 8 brocche - Il corso di Qi Gong moderno I\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/qi-gong-kurs-8-brokate-07-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corsi video online di Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Gong moderno 8 broccati con Wolfgang\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-800x1130.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-600x847.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i.jpg 1062w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Il corso moderno di Qi Gong 8 Broccato di una vita semplicemente migliore\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1416\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-8-brokate\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Le 8 brocche - Il corso di Qi Gong moderno I<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1416\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/weidinger-w08-warme-mitte\/\" aria-label=\"Weidinger W08 - Centro caldo\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-1-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" aria-hidden=\"true\" title=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" \/><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1295\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tWeidinger\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/weidinger-w08-warme-mitte\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Weidinger W08 - Centro caldo<\/a><\/p><p class=\"woocommerce-loop-product__subtitle wp-subtitle\">Miscela di erbe della MTC<\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>62,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1295\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-3901745 > .col-inner {\n  max-width: 1200px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1538159648 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n<style>\nh2 {\ntext-align: left;\n}\n\nsection.one-image .img {\nmargin-bottom: 0 !important;\n}\n\nsection.one-image img {\n    border-radius: 15px;\n}\n<\/style>\n\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Sentite questa UNRUHE interiore che non vuole saperne di smettere?<br \/>\nI vostri pensieri saltano da un argomento all'altro.<br \/>\nIl corpo \u00e8 teso.<br \/>\nSi vorrebbe solo spegnere, ma non ci si riesce.<\/p>","protected":false},"author":3859,"featured_media":17596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[300],"tags":[],"class_list":["post-17595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tcm-tipp-der-woche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Innere Unruhe l\u00f6sen | TCM\u2013Techniken f\u00fcr mehr Ruhe<\/title>\n<meta name=\"description\" content=\"Entdecke 3 TCM\u2013Methoden gegen innere Unruhe: Meridian\u2013Klopfen, Visualisierung und Atemtechnik f\u00fcr mehr Balance. \u2713\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meine-tcm.com\/it\/dallinquietudine-alla-forza-interiore-il-percorso-tcm-verso-la-serenita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innere Unruhe l\u00f6sen | TCM\u2013Techniken f\u00fcr mehr Ruhe\" \/>\n<meta property=\"og:description\" content=\"Entdecke 3 TCM\u2013Methoden gegen innere Unruhe: Meridian\u2013Klopfen, Visualisierung und Atemtechnik f\u00fcr mehr Balance. \u2713\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meine-tcm.com\/it\/dallinquietudine-alla-forza-interiore-il-percorso-tcm-verso-la-serenita\/\" \/>\n<meta property=\"og:site_name\" content=\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-26T05:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"2160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/\"},\"author\":{\"name\":\"Marina\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/76da350caed5aad1d9998ba607d86f28\"},\"headline\":\"Von Unruhe zu innerer Kraft: Der TCM\u2013Weg zur Gelassenheit\",\"datePublished\":\"2025-03-26T05:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/\"},\"wordCount\":805,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/unruhe-holz-element.jpg\",\"articleSection\":[\"TCM Tipp der Woche\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/\",\"name\":\"Innere Unruhe l\u00f6sen | TCM\u2013Techniken f\u00fcr mehr Ruhe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/unruhe-holz-element.jpg\",\"datePublished\":\"2025-03-26T05:30:00+00:00\",\"description\":\"Entdecke 3 TCM\u2013Methoden gegen innere Unruhe: Meridian\u2013Klopfen, Visualisierung und Atemtechnik f\u00fcr mehr Balance. \u2713\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/unruhe-holz-element.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/unruhe-holz-element.jpg\",\"width\":2160,\"height\":2160,\"caption\":\"Die Unruhe vergeht, wenn du der Stille Raum gibst.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meine-tcm.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von Unruhe zu innerer Kraft: Der TCM\u2013Weg zur Gelassenheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"name\":\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\",\"description\":\"Einfach gesund bleiben\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meine-tcm.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\",\"name\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"width\":559,\"height\":479,\"caption\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/meinetcm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EinfachbesserLeben\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/76da350caed5aad1d9998ba607d86f28\",\"name\":\"Marina\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sciogliere l'inquietudine interiore | Tecniche di MTC per una maggiore calma","description":"Scoprite 3 metodi della MTC contro l'inquietudine interiore: picchiettamento dei meridiani, tecniche di visualizzazione e respirazione per un maggiore equilibrio. \u2713","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meine-tcm.com\/it\/dallinquietudine-alla-forza-interiore-il-percorso-tcm-verso-la-serenita\/","og_locale":"it_IT","og_type":"article","og_title":"Innere Unruhe l\u00f6sen | TCM\u2013Techniken f\u00fcr mehr Ruhe","og_description":"Entdecke 3 TCM\u2013Methoden gegen innere Unruhe: Meridian\u2013Klopfen, Visualisierung und Atemtechnik f\u00fcr mehr Balance. \u2713","og_url":"https:\/\/www.meine-tcm.com\/it\/dallinquietudine-alla-forza-interiore-il-percorso-tcm-verso-la-serenita\/","og_site_name":"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt","article_published_time":"2025-03-26T05:30:00+00:00","og_image":[{"width":2160,"height":2160,"url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element.jpg","type":"image\/jpeg"}],"author":"Marina","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Marina","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/#article","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/"},"author":{"name":"Marina","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/76da350caed5aad1d9998ba607d86f28"},"headline":"Von Unruhe zu innerer Kraft: Der TCM\u2013Weg zur Gelassenheit","datePublished":"2025-03-26T05:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/"},"wordCount":805,"commentCount":2,"publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"image":{"@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element.jpg","articleSection":["TCM Tipp der Woche"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/","url":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/","name":"Sciogliere l'inquietudine interiore | Tecniche di MTC per una maggiore calma","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/#primaryimage"},"image":{"@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element.jpg","datePublished":"2025-03-26T05:30:00+00:00","description":"Scoprite 3 metodi della MTC contro l'inquietudine interiore: picchiettamento dei meridiani, tecniche di visualizzazione e respirazione per un maggiore equilibrio. \u2713","breadcrumb":{"@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/#primaryimage","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element.jpg","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/02\/unruhe-holz-element.jpg","width":2160,"height":2160,"caption":"Die Unruhe vergeht, wenn du der Stille Raum gibst."},{"@type":"BreadcrumbList","@id":"https:\/\/www.meine-tcm.com\/von-unruhe-zu-innerer-kraft-der-tcm-weg-zur-gelassenheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meine-tcm.com\/"},{"@type":"ListItem","position":2,"name":"Von Unruhe zu innerer Kraft: Der TCM\u2013Weg zur Gelassenheit"}]},{"@type":"WebSite","@id":"https:\/\/www.meine-tcm.com\/#website","url":"https:\/\/www.meine-tcm.com\/","name":"la mia MTC | Medicina Tradizionale Cinese spiegata in modo semplice","description":"Rimanere semplicemente in salute","publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meine-tcm.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.meine-tcm.com\/#organization","name":"meine-TCM.com - La Medicina Tradizionale Cinese spiegata in modo semplice","url":"https:\/\/www.meine-tcm.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","width":559,"height":479,"caption":"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt"},"image":{"@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/meinetcm\/","https:\/\/www.youtube.com\/@EinfachbesserLeben"]},{"@type":"Person","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/76da350caed5aad1d9998ba607d86f28","name":"Marina"}]}},"wps_subtitle":"Wie du Anspannung in neue Energie verwandelst","_links":{"self":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts\/17595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/users\/3859"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/comments?post=17595"}],"version-history":[{"count":0,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts\/17595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/media\/17596"}],"wp:attachment":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/media?parent=17595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/categories?post=17595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/tags?post=17595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}