{"id":1112,"date":"2020-10-07T11:07:18","date_gmt":"2020-10-07T09:07:18","guid":{"rendered":"https:\/\/www.meine-tcm.com\/?p=1112"},"modified":"2022-08-14T21:08:11","modified_gmt":"2022-08-14T19:08:11","slug":"7-consigli-per-un-sonno-migliore","status":"publish","type":"post","link":"https:\/\/www.meine-tcm.com\/it\/7-tipps-fuer-einen-besseren-schlaf\/","title":{"rendered":"7 consigli per dormire meglio"},"content":{"rendered":"<section class=\"section main-teaser\" id=\"section_441774102\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-2128316367\">\n\n\n\t<div id=\"col-562310263\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"teaser\">I problemi del sonno sono molto comuni e chiunque ne sia affetto sa quanto possa essere stressante. In MTC, di solito si cura sempre la radice del problema. Se qualcuno ha problemi di sonno, tuttavia, ci discostiamo da questa strategia e in questo caso trattiamo prima il sintomo.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-562310263 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_441774102 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-673770955\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-673770955 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section one-image\" id=\"section_1455826290\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1551517972\">\n\n\n\t<div id=\"col-925976453\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover rounded-corner has-parallax\" id=\"banner-566908494\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-1\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/09\/tcm-fuer-einen-besseren-schlaf-02-1920x1280-1-1200x800.jpg\" class=\"bg attachment-large size-large\" alt=\"Giovane donna con capelli castano scuro si sdraia sulla pelliccia e dorme\" title=\"Il Qi Gong per dormire meglio\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1247309498\" class=\"text-box banner-layer hidden x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h3 class=\"uppercase\"><strong>Questo \u00e8 un semplice banner<\/strong><\/h3>\n<p>Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat.<\/p>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1247309498 {\n  width: 60%;\n}\n#text-box-1247309498 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-566908494 {\n  padding-top: 520px;\n}\n<\/style>\n  <\/div>\n\n\n<p class=\"caption\">Finalmente si dorme meglio<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-925976453 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1455826290 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1234312302\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1234312302 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section list\" id=\"section_733079124\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1297771732\">\n\n\n\t<div id=\"col-880136458\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h2>Con questi consigli potrete finalmente dormire<\/h2>\n<ul class=\"check\">\n<li><strong>Suggerimento 1: esercizio fisico sufficiente. <\/strong>In questo modo \u00e8 molto facile spegnere la mente. Una passeggiata pu\u00f2 essere sufficiente. L'allenamento di resistenza \u00e8 ideale perch\u00e9 comporta movimenti monotoni e permette di spegnere la mente.&nbsp;<br>Gli esercizi di Qi Gong sono eccellenti anche perch\u00e9 calmano il sistema nervoso e bilanciano naturalmente le energie del corpo.&nbsp;<\/li>\n<li class=\"red\"><strong>Suggerimento 2: Cellulare, TV e tablet <\/strong>non dovrebbero trovarsi in camera da letto! Secondo le ultime ricerche, gli schermi emettono luce a onde blu, che ha un effetto negativo sulla secrezione di melatonina e quindi sul sonno.&nbsp;<br>\u00c8 quindi un vantaggio che la camera da letto sia il pi\u00f9 possibile buia.&nbsp;<br>E girate la sveglia in modo da non poter guardare il display.&nbsp;<\/li>\n<li><strong>Suggerimento 3: non mangiare troppo o troppo grasso la sera. <\/strong>Se gli organi devono digerire di notte, il corpo non pu\u00f2 riposare. Se possibile, mangiate qualcosa di leggero a quest'ora del giorno, come riso e verdure o zuppe.&nbsp;<br>Anche l'alcol non migliora necessariamente il sonno. L'alcol disturba le fasi di sonno profondo che normalmente si ripetono ogni 90 minuti. Di conseguenza, al mattino non siamo veramente riposati e ci sentiamo esausti.&nbsp;&nbsp;<\/li>\n<li><strong>Suggerimento 4: scrivere un diario.<\/strong> Se vi passano per la testa molte cose, sar\u00e0 impossibile spegnerle. Perch\u00e9 continuerete inconsciamente a pensarci.&nbsp; &nbsp;<br>Crediamo che il continuo rimuginare risolva i problemi. Ma la soluzione arriva nelle pause di riflessione, quando riusciamo a schiarirci le idee. Ecco perch\u00e9 pu\u00f2 essere utile tenere un diario. Poco prima di andare a dormire, scrivete i vostri pensieri, chiudetelo consapevolmente e mettetelo via. Questo permette anche di lasciar andare i pensieri.&nbsp;<\/li>\n<li><strong>Suggerimento 5: Esercizi di respirazione<\/strong> sono un modo straordinariamente semplice per rilassare il sistema nervoso e addormentarsi facilmente. La respirazione addominale profonda \u00e8 particolarmente indicata.&nbsp;<br>Pancia in dentro quando si espira e pancia in fuori quando si inspira.&nbsp;<br>Per i praticanti avanzati, esiste uno speciale esercizio di respirazione chiamato 4-7-8.&nbsp;<br>Respiriamo con un ritmo speciale che richiede maggiore attenzione. Si dice che questo esercizio yoga abbia un effetto profondo sul sistema nervoso.&nbsp;&nbsp;<br>Inspiriamo dal naso per 4 secondi, tratteniamo il respiro per 7 secondi ed espiriamo per 8 secondi. Eseguiamo questa operazione per 4-8 volte di seguito.&nbsp;<\/li>\n<li><strong>Suggerimento 6: creare un'atmosfera piacevole.<\/strong> Anche un'atmosfera piacevole in camera da letto favorisce il sonno.&nbsp;&nbsp;<br>L'aria fresca fa molto bene. Lasciate quindi la finestra aperta. Se non \u00e8 possibile, ventilate bene la sera.&nbsp;<br>Eliminate tutto ci\u00f2 che vi ricorda il lavoro. Pu\u00f2 trattarsi anche di una pila di riviste o di libri che avete intenzione di leggere da un anno. Il solo vederli vi fa sentire in colpa. Quindi, sbarazzatevene!&nbsp;<br>Anche la pila di panni e il ferro da stiro non ricordano i sogni d'oro!&nbsp;<br>Si dice che la lavanda, come profumo in camera da letto, abbia anche un effetto che induce il sonno. Provate!<\/li>\n<li><strong>Suggerimento 7: meditare una volta al giorno.<\/strong> La meditazione \u00e8 anche un modo ideale per prepararsi a un buon sonno, perch\u00e9 permette di calmare i pensieri in modo naturale.&nbsp;<br>Nel prossimo video vi mostrer\u00f2 una forma speciale di meditazione.&nbsp;<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-880136458 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_733079124 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-2001859970\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2001859970 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<div id=\"gap-155213978\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-155213978 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section\" id=\"section_975440976\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1789334907\">\n\n\n\t<div id=\"col-1812562734\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<p><iframe loading=\"lazy\" scrolling=\"no\" allow=\"autoplay\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/881758504&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\"><\/iframe><\/p>\n<div style=\"font-size: 10px; color: #cccccc;line-break: anywhere;word-break: normal;overflow: hidden;white-space: nowrap;text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif;font-weight: 100;\"><a href=\"https:\/\/soundcloud.com\/user-179907194-117651527\" title=\"la mia MTC\" target=\"_blank\" style=\"color: #cccccc; text-decoration: none;\" rel=\"noopener noreferrer\">la mia MTC<\/a> - <a href=\"https:\/\/soundcloud.com\/user-179907194-117651527\/mediation-den-atem-beobachten\" title=\"Mediazione: osservare il respiro\" target=\"_blank\" style=\"color: #cccccc; text-decoration: none;\" rel=\"noopener noreferrer\">Mediazione: osservare il respiro<\/a><\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1812562734 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_975440976 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1502408145\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1502408145 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section blogpostlist\" id=\"section_1098560028\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-352905112\">\n\n\n\t<div id=\"col-47195427\" class=\"col blogpostscarousel small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h2>I nostri post pi\u00f9 popolari<\/h2>\n\n  \n    <div class=\"row large-columns-5 medium-columns-3 small-columns-1 slider row-slider slider-nav-simple slider-nav-outside slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/die-herz-zeit-nutzen\/\" class=\"plain\" aria-label=\"Die Herz\u2013Zeit nutzen\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/die-herz-zeit-nutzen\/\" class=\"plain\">Die Herz\u2013Zeit nutzen<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wenn-hitze-krank-macht\/\" class=\"plain\" aria-label=\"Quando il caldo fa ammalare\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Il sole d\u00e0 la vita. Ma pu\u00f2 anche toglierla, se non ti proteggi.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Il sole d\u00e0 la vita. Ma pu\u00f2 anche toglierla, se non ti proteggi.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wenn-hitze-krank-macht\/\" class=\"plain\">Quando il caldo fa ammalare<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\" aria-label=\"Perch\u00e9 la pancia si ribella in estate\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Il cuore sa ci\u00f2 che la mente non riesce a esprimere. Ascoltalo.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Il cuore sa ci\u00f2 che la mente non riesce a esprimere. Ascoltalo.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\">Perch\u00e9 la pancia si ribella in estate<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\" aria-label=\"Perch\u00e9 l&#039;estate mette a dura prova la circolazione \u2014 e cosa consiglia la MTC per ovviare a questo problema\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-533x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Q\u00ed B\u00f3 | L&#039;imperatore giallo Huangdi | Dr. Weber\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-533x400.jpg 533w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-768x576.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-16x12.jpg 16w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-800x600.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1.jpg 1066w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" title=\"Servizio fotografico \u201cChiedi all\u2019Imperatore Giallo\u201d (BTS) \u2013 luglio 2026\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\">Perch\u00e9 l'estate mette a dura prova la circolazione \u2014 e cosa consiglia la MTC per ovviare a questo problema<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\" aria-label=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"La bevanda estiva Yin \u2014 il segreto degli antichi maestri\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\">La bevanda estiva Yin \u2014 il segreto degli antichi maestri<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/schlafprobleme-im-sommer\/\" class=\"plain\" aria-label=\"Problemi di sonno in estate\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Non \u00e8 il caldo a privarti del sonno. \u00c8 uno spirito che non pu\u00f2 trovare pace.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Non \u00e8 il caldo a privarti del sonno. \u00c8 uno spirito che non pu\u00f2 trovare pace.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/schlafprobleme-im-sommer\/\" class=\"plain\">Problemi di sonno in estate<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\" aria-label=\"Perch\u00e9 in estate sei pi\u00f9 irritabile \u2014 il \u201cfuoco del fegato\u201d nella MTC\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Tu non sei cos\u00ec. Ma in questo momento ti senti estraneo a te stesso.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Tu non sei cos\u00ec. Ma in questo momento ti senti estraneo a te stesso.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\">Perch\u00e9 in estate sei pi\u00f9 irritabile \u2014 il \u201cfuoco del fegato\u201d nella MTC<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item has-post-icon\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\" aria-label=\"RITIRO: Qi Gong e respirazione TAO (marzo 2027)\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"534\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-534x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-534x400.jpg 534w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-768x576.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-16x12.jpg 16w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-800x600.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview.jpg 1067w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" title=\"Retiro di qigong in primavera in Tirolo - Anteprima\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t\t\t<div class=\"absolute no-click x50 y50 md-x50 md-y50 lg-x50 lg-y50\">\n  \t\t\t\t            \t<div class=\"overlay-icon\">\n  \t\t\t\t                    <i class=\"icon-play\" aria-hidden=\"true\"><\/i>  \t\t\t\t                <\/div>\n  \t\t\t\t            <\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\">RITIRO: Qi Gong e respirazione TAO (marzo 2027)<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/deine-sommer-apotheke\/\" class=\"plain\" aria-label=\"La tua farmacia estiva\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"La tua farmacia cresce nel giardino. Devi solo sapere cosa raccogliere.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-2-sommer-apotheke-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"La tua farmacia cresce nel giardino. Devi solo sapere cosa raccogliere.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/deine-sommer-apotheke\/\" class=\"plain\">La tua farmacia estiva<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/so-werden-tcm-kraeutermischungen-erstellt\/\" class=\"plain\" aria-label=\"Ecco come vengono preparate le miscele di erbe della MTC\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/04\/hero-tcm-apotheke-seeds-960-533x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Antica farmacia di medicina tradizionale cinese, bancone con le 5 erbe per la miscela Suan Zao Ren Tang\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/04\/hero-tcm-apotheke-seeds-960-533x400.jpg 533w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/04\/hero-tcm-apotheke-seeds-960-800x600.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/04\/hero-tcm-apotheke-seeds-960-768x576.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/04\/hero-tcm-apotheke-seeds-960-16x12.jpg 16w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/04\/hero-tcm-apotheke-seeds-960.jpg 960w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" title=\"Spiegazione delle miscele di erbe della MTC\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/so-werden-tcm-kraeutermischungen-erstellt\/\" class=\"plain\">Ecco come vengono preparate le miscele di erbe della MTC<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommer-und-dein-herz\/\" class=\"plain\" aria-label=\"L&#039;estate e il tuo cuore\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"L&#039;estate appartiene al cuore. E il cuore ha bisogno di qualcosa di pi\u00f9 del sole.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/juni-Beitrag-1-her-tcm-2-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"L&#039;estate appartiene al cuore. E il cuore ha bisogno di qualcosa di pi\u00f9 del sole.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sommer-und-dein-herz\/\" class=\"plain\">L'estate e il tuo cuore<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/du-bist-nicht-muede-du-bist-ueberfuettert\/\" class=\"plain\" aria-label=\"Non sei stanco. Hai mangiato troppo.\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"536\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/Juni-Herz-Sommer-Team-des-Gelben-Kiasers-Shooting-Juni-02-1066-536x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"L&#039;Imperatore Giallo Huangdi | Q\u00ed B\u00f3 | Dr. Weber\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/Juni-Herz-Sommer-Team-des-Gelben-Kiasers-Shooting-Juni-02-1066-536x400.jpg 536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/Juni-Herz-Sommer-Team-des-Gelben-Kiasers-Shooting-Juni-02-1066-768x573.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/Juni-Herz-Sommer-Team-des-Gelben-Kiasers-Shooting-Juni-02-1066-16x12.jpg 16w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/Juni-Herz-Sommer-Team-des-Gelben-Kiasers-Shooting-Juni-02-1066-800x597.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/Juni-Herz-Sommer-Team-des-Gelben-Kiasers-Shooting-Juni-02-1066.jpg 1066w\" sizes=\"auto, (max-width: 536px) 100vw, 536px\" title=\"Servizio fotografico &quot;Chiedi all&#039;Imperatore Giallo&quot; (BTS) - giugno 2026\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/du-bist-nicht-muede-du-bist-ueberfuettert\/\" class=\"plain\">Non sei stanco. Hai mangiato troppo.<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/7-tage-reset-gegen-reizueberflutung\/\" class=\"plain\" aria-label=\"7 giorni per ricominciare da capo e combattere il sovraccarico sensoriale\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Il controllo non inizia con la rinuncia, ma con un istante.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/05\/dopamin-scrolling-werkzeuge-100x100.jpg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Il controllo non inizia con la rinuncia, ma con un istante.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/7-tage-reset-gegen-reizueberflutung\/\" class=\"plain\">7 giorni per ricominciare da capo e combattere il sovraccarico sensoriale<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/herzklopfen-ohne-grund-da-ist-ein-grund\/\" class=\"plain\" aria-label=\"Palpitazioni senza motivo? In realt\u00e0 c&#039;\u00e8 un motivo\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Quando il cuore si fa sentire, non vuole disturbare, vuole solo esprimersi.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/02\/herklopfen-mai-beitrag-3-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Quando il cuore si fa sentire, non vuole disturbare, vuole solo esprimersi.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/herzklopfen-ohne-grund-da-ist-ein-grund\/\" class=\"plain\">Palpitazioni senza motivo? In realt\u00e0 c'\u00e8 un motivo<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sozial-muede-wenn-naehe-erschoepft\/\" class=\"plain\" aria-label=\"Stanchezza sociale \u2014 Quando la vicinanza stanca\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Non tutto il silenzio \u00e8 solitudine. A volte \u00e8 protezione.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/01\/soziale-grenzen-mai-beitrag-2-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Non tutto il silenzio \u00e8 solitudine. A volte \u00e8 protezione.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:0 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/sozial-muede-wenn-naehe-erschoepft\/\" class=\"plain\">Stanchezza sociale \u2014 Quando la vicinanza stanca<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-47195427 > .col-inner {\n  max-width: 1200px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1098560028 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section longline\" id=\"section_1114446051\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1504669563\">\n\n\n\t<div id=\"col-1000720212\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<hr>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1000720212 > .col-inner {\n  max-width: 1000px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1114446051 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_243429511\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1953936103\">\n\n\n\t<div id=\"col-1530626389\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Imparare il Qi Gong facilmente online con i nostri corsi popolari<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1530626389 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_243429511 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-952101771\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-952101771 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section top-produkte\" id=\"section_1627857640\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1521212831\">\n\n\n\t<div id=\"col-1975734005\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t\n  \n    <div class=\"row  equalize-box large-columns-5 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" aria-label=\"Corso di Qi Gong per principianti e studenti leggermente avanzati\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-fuer-anfaenger-06-online-ansehen-mobile-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corso di Qi Gong per principianti da Einfach besser leben Online\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Gong per principianti con Wolfgang nell&#039;immagine\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Corso di Qi Gong per principianti da Einfach besser leben\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1368\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Corso di Qi Gong per principianti e studenti leggermente avanzati<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1368\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" aria-label=\"AkuPen - l&#039;ingegnosa penna per agopuntura con istruzioni video\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-weiss-vertikal-3-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"AkuPen aperto\" aria-hidden=\"true\" title=\"AkuPen da Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"AukPen con confezione in legno\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled-800x1131.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1087x1536.jpg 1087w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1449x2048.jpg 1449w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-8x12.jpg 8w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled.jpg 1811w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"AkuPen con istruzioni video\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1365\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tAkuPen\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">AkuPen - l'ingegnosa penna per agopuntura con istruzioni video<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>80,57&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1365\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" aria-label=\"Corso di Qi Gong II - Le 18 figure dell&#039;armonia\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-05-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corsi video online di Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Qong moderno - Le 18 figure dell&#039;armonia\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Corso di Qi Qong - Le 18 figure dell&#039;armonia\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1376\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Corso di Qi Gong II - Le 18 figure dell'armonia<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>35,19&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1376\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-8-brokate\/\" aria-label=\"Le 8 brocche - Il corso di Qi Gong moderno I\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/qi-gong-kurs-8-brokate-07-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La mano tiene lo smartphone, sullo schermo il portale dei corsi online di Einfach besser leben\" aria-hidden=\"true\" title=\"Corsi video online di Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Immagine di copertina del corso di Qi Gong moderno 8 broccati con Wolfgang\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-800x1130.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-600x847.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i.jpg 1062w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Il corso moderno di Qi Gong 8 Broccato di una vita semplicemente migliore\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1416\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/qi-gong-kurs-8-brokate\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Le 8 brocche - Il corso di Qi Gong moderno I<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1416\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/weidinger-w08-warme-mitte\/\" aria-label=\"Weidinger W08 - Centro caldo\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-1-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" aria-hidden=\"true\" title=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" \/><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Miscela di erbe MTC W08 - Centro caldo del Dr. Weidinger\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1295\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Anteprima<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tWeidinger\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/it\/produkt\/weidinger-w08-warme-mitte\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Weidinger W08 - Centro caldo<\/a><\/p><p class=\"woocommerce-loop-product__subtitle wp-subtitle\">Miscela di erbe della MTC<\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>62,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1295\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1975734005 > .col-inner {\n  max-width: 1200px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1627857640 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-840563516\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-840563516 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section newsletter\" id=\"section_2104459202\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-74414019\">\n\n\n\t<div id=\"col-1377732145\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2096941739\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/08\/wolfgang-von-ebl.png\" class=\"attachment-medium size-medium\" alt=\"Ritratto di Wolfgang\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/08\/wolfgang-von-ebl.png 360w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/08\/wolfgang-von-ebl-100x100.png 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/08\/wolfgang-von-ebl-280x280.png 280w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" title=\"Wolfgang di EBL - il mio TCM\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2096941739 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1377732145 > .col-inner {\n  max-width: 180px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-637872002\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h4 class=\"newsletter-heading\">Newsletter<\/h4>\n<p class=\"text-left\">Rimanete aggiornati con la nostra newsletter. Oltre a consigli e trucchi utili per l'allenamento e la vita di tutti i giorni, non perderete nessuna delle nostre novit\u00e0.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-637872002 > .col-inner {\n  max-width: 410px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-518332145\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<!-- Begin Mailchimp Signup Form -->\r\n<div id=\"mc_embed_signup\">\r\n<form action=\"https:\/\/www.meine-tcm.com\/it\/registrazione-alla-newsletter\/\" method=\"get\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" novalidate data-trp-original-action=\"https:\/\/www.meine-tcm.com\/newsletter-anmeldung\/\">\r\n    <div id=\"mc_embed_signup_scroll\">\r\n\t\r\n<div class=\"mc-field-group\">\r\n\t<label for=\"mce-EMAIL\"><\/label>\r\n\t<input type=\"email\" value=\"\" name=\"email\" class=\"required email\" id=\"mce-EMAIL\" placeholder=\"Un indirizzo e-mail\">\r\n<\/div>\r\n\t<div id=\"mce-responses\" class=\"clear\">\r\n\t\t<div class=\"response\" id=\"mce-error-response\" style=\"display:none\"><\/div>\r\n\t\t<div class=\"response\" id=\"mce-success-response\" style=\"display:none\"><\/div>\r\n\t<\/div>\r\n    <div style=\"position: absolute; left: -5000px;\" aria-hidden=\"true\"><input type=\"text\" name=\"b_abb51f2fb827371efab83c9b8_53a63900d3\" tabindex=\"-1\" value=\"\"><\/div>\r\n    <div class=\"clear\"><input type=\"submit\" value=\"Iscriviti ora\" name=\"subscribe\" id=\"mc-embedded-subscribe\" class=\"button\"><\/div>\r\n    <\/div>\r\n<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\r\n<\/div>\r\n\r\n<!--End mc_embed_signup-->\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-518332145 > .col-inner {\n  max-width: 290px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2104459202 {\n  padding-top: 40px;\n  padding-bottom: 40px;\n  background-color: rgba(0, 121, 140, 0.2);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-974162012\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-974162012 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>I problemi del sonno sono molto comuni e chiunque ne sia affetto sa quanto possa essere stressante. In MTC, di solito si cura sempre la radice del problema. Tuttavia, se qualcuno ha problemi di sonno, ci si discosta da questa strategia e si cura prima il sintomo.<\/p>","protected":false},"author":1943,"featured_media":2073,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[213],"class_list":["post-1112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-schlafprobleme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 Tipps f\u00fcr Einen Besseren Schlaf<\/title>\n<meta name=\"description\" content=\"Mit diesen 7 Tipps wirst du garantiert besser Ein\u2013 und auch Durchschlafen. Schlafen kann man lernen. Wir zeigen dir wie es geht!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meine-tcm.com\/it\/7-consigli-per-un-sonno-migliore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 Tipps f\u00fcr Einen Besseren Schlaf\" \/>\n<meta property=\"og:description\" content=\"Mit diesen 7 Tipps wirst du garantiert besser Ein\u2013 und auch Durchschlafen. Schlafen kann man lernen. Wir zeigen dir wie es geht!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meine-tcm.com\/it\/7-consigli-per-un-sonno-migliore\/\" \/>\n<meta property=\"og:site_name\" content=\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-07T09:07:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-14T19:08:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/09\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wolfgang Stemer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wolfgang Stemer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/\"},\"author\":{\"name\":\"Wolfgang Stemer\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/9297496a1d5d1d219f35ba63197be54e\"},\"headline\":\"7 Tipps f\u00fcr Einen Besseren Schlaf\",\"datePublished\":\"2020-10-07T09:07:18+00:00\",\"dateModified\":\"2022-08-14T19:08:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/\"},\"wordCount\":1099,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg\",\"keywords\":[\"Schlafprobleme\"],\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/\",\"name\":\"7 Tipps f\u00fcr Einen Besseren Schlaf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg\",\"datePublished\":\"2020-10-07T09:07:18+00:00\",\"dateModified\":\"2022-08-14T19:08:11+00:00\",\"description\":\"Mit diesen 7 Tipps wirst du garantiert besser Ein\u2013 und auch Durchschlafen. Schlafen kann man lernen. Wir zeigen dir wie es geht!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg\",\"width\":920,\"height\":768,\"caption\":\"Qi Gong f\u00fcr einen besseren Schlaf\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/7-tipps-fuer-einen-besseren-schlaf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meine-tcm.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 Tipps f\u00fcr Einen Besseren Schlaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"name\":\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\",\"description\":\"Einfach gesund bleiben\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meine-tcm.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\",\"name\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"width\":559,\"height\":479,\"caption\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/meinetcm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EinfachbesserLeben\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/9297496a1d5d1d219f35ba63197be54e\",\"name\":\"Wolfgang Stemer\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 consigli per dormire meglio","description":"Con questi 7 consigli, \u00e8 garantito che vi addormenterete e dormirete meglio durante la notte. Si pu\u00f2 imparare a dormire. Vi mostriamo come!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meine-tcm.com\/it\/7-consigli-per-un-sonno-migliore\/","og_locale":"it_IT","og_type":"article","og_title":"7 Tipps f\u00fcr Einen Besseren Schlaf","og_description":"Mit diesen 7 Tipps wirst du garantiert besser Ein\u2013 und auch Durchschlafen. Schlafen kann man lernen. Wir zeigen dir wie es geht!","og_url":"https:\/\/www.meine-tcm.com\/it\/7-consigli-per-un-sonno-migliore\/","og_site_name":"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt","article_published_time":"2020-10-07T09:07:18+00:00","article_modified_time":"2022-08-14T19:08:11+00:00","og_image":[{"width":920,"height":768,"url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/09\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg","type":"image\/jpeg"}],"author":"Wolfgang Stemer","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Wolfgang Stemer","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/#article","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/"},"author":{"name":"Wolfgang Stemer","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/9297496a1d5d1d219f35ba63197be54e"},"headline":"7 Tipps f\u00fcr Einen Besseren Schlaf","datePublished":"2020-10-07T09:07:18+00:00","dateModified":"2022-08-14T19:08:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/"},"wordCount":1099,"commentCount":3,"publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"image":{"@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/09\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg","keywords":["Schlafprobleme"],"articleSection":["Allgemein"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/","url":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/","name":"7 consigli per dormire meglio","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/#primaryimage"},"image":{"@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/09\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg","datePublished":"2020-10-07T09:07:18+00:00","dateModified":"2022-08-14T19:08:11+00:00","description":"Con questi 7 consigli, \u00e8 garantito che vi addormenterete e dormirete meglio durante la notte. Si pu\u00f2 imparare a dormire. Vi mostriamo come!","breadcrumb":{"@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/#primaryimage","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/09\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2020\/09\/tcm-fuer-einen-besseren-schlaf-02-920x768-1.jpg","width":920,"height":768,"caption":"Qi Gong f\u00fcr einen besseren Schlaf"},{"@type":"BreadcrumbList","@id":"https:\/\/www.meine-tcm.com\/7-tipps-fuer-einen-besseren-schlaf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meine-tcm.com\/"},{"@type":"ListItem","position":2,"name":"7 Tipps f\u00fcr Einen Besseren Schlaf"}]},{"@type":"WebSite","@id":"https:\/\/www.meine-tcm.com\/#website","url":"https:\/\/www.meine-tcm.com\/","name":"la mia MTC | Medicina Tradizionale Cinese spiegata in modo semplice","description":"Rimanere semplicemente in salute","publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meine-tcm.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.meine-tcm.com\/#organization","name":"meine-TCM.com - La Medicina Tradizionale Cinese spiegata in modo semplice","url":"https:\/\/www.meine-tcm.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","width":559,"height":479,"caption":"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt"},"image":{"@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/meinetcm\/","https:\/\/www.youtube.com\/@EinfachbesserLeben"]},{"@type":"Person","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/9297496a1d5d1d219f35ba63197be54e","name":"Wolfgang Stemer"}]}},"wps_subtitle":"Endlich besser schlafen","_links":{"self":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts\/1112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/users\/1943"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/comments?post=1112"}],"version-history":[{"count":0,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/posts\/1112\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/media\/2073"}],"wp:attachment":[{"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/media?parent=1112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/categories?post=1112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/it\/wp-json\/wp\/v2\/tags?post=1112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}