{"id":19052,"date":"2025-06-18T07:00:00","date_gmt":"2025-06-18T05:00:00","guid":{"rendered":"https:\/\/www.meine-tcm.com\/?p=19052"},"modified":"2025-06-04T12:32:00","modified_gmt":"2025-06-04T10:32:00","slug":"anxiete-et-depression-du-point-de-vue-de-la-tcm","status":"publish","type":"post","link":"https:\/\/www.meine-tcm.com\/fr\/angst-und-depressionen-aus-sicht-der-tcm\/","title":{"rendered":"Anxi\u00e9t\u00e9 et d\u00e9pression du point de vue de la MTC"},"content":{"rendered":"<section class=\"section main-teaser\" id=\"section_1671506847\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1081873599\">\n\n\n\t<div id=\"col-1976664797\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"teaser\">de la peur. La tristesse. Le vide int\u00e9rieur.<br>Pour de nombreuses personnes, ces sentiments ne sont pas une phase \u00e0 court terme, mais un \u00e9tat permanent p\u00e9nible. En m\u00e9decine traditionnelle chinoise (MTC), on ne consid\u00e8re pas ces \u00e9tats \u00e9motionnels comme des probl\u00e8mes psychiques isol\u00e9s, mais comme l'expression d'un flux \u00e9nerg\u00e9tique perturb\u00e9 dans le corps - en particulier dans les circuits fonctionnels du c\u0153ur, du foie, de la rate, des reins et des poumons.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1976664797 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1671506847 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-13177608\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-13177608 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section one-image\" id=\"section_1487281297\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-551725725\">\n\n\n\t<div id=\"col-697702429\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1564796212\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"2160\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen.jpg\" class=\"attachment-original size-original\" alt=\"La peur te retient \u00e0 la branche. Mais ton \u00eatre est fait pour le vol\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen.jpg 2160w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen-12x12.jpg 12w\" sizes=\"auto, (max-width: 2160px) 100vw, 2160px\" title=\"La peur te retient \u00e0 la branche. Mais ton \u00eatre est fait pour le vol\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1564796212 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p class=\"caption\">La peur te retient \u00e0 la branche. Mais ton \u00eatre est fait pour le vol<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-697702429 > .col-inner {\n  border-radius: 10px;\n  max-width: 640px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1487281297 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-2078154057\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2078154057 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section text\" id=\"section_581889743\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-2312313\">\n\n\n\t<div id=\"col-1379913981\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h2>\ud83c\udf3f Les \u00e9motions sont de l'\u00e9nergie - et elles veulent circuler<\/h2>\n<p>Dans la MTC, le corps, l'esprit et l'\u00e2me sont indissociables. Les \u00e9motions sont consid\u00e9r\u00e9es comme des forces naturelles - mais elles peuvent aussi rendre malade si elles stagnent pendant une longue p\u00e9riode, si elles sont r\u00e9prim\u00e9es ou si elles sont v\u00e9cues de mani\u00e8re excessive. Selon la MTC, l'anxi\u00e9t\u00e9 et la d\u00e9pression apparaissent lorsque le Qi (\u00e9nergie vitale) ne peut pas circuler librement ou lorsque certains organes sont en d\u00e9s\u00e9quilibre \u00e9nerg\u00e9tique.<\/p>\n<h2>\ud83e\udec0 C\u0153ur - si\u00e8ge du shen (esprit et conscience)<\/h2>\n<p>Dans la MTC, le c\u0153ur est bien plus qu'une simple pompe. Il est le si\u00e8ge du \"shen\", ta conscience, ta pr\u00e9sence, ta joie de vivre.<\/p>\n<p>Un Qi du c\u0153ur \u00e9quilibr\u00e9 apporte<\/p>\n<ul>\n<li>Joie de vivre<\/li>\n<li>clart\u00e9 mentale<\/li>\n<li>un esprit calme<\/li>\n<\/ul>\n<p>Si le c\u0153ur est affaibli - par exemple par le surmenage, la tristesse ou<br>agitation int\u00e9rieure - se manifestent souvent :<\/p>\n<ul>\n<li>vide int\u00e9rieur<\/li>\n<li>Troubles du sommeil<\/li>\n<li>Manque de joie<\/li>\n<li>Irritabilit\u00e9 ou pleurnicherie<\/li>\n<\/ul>\n<p>C\u0153ur-Feu en \u00e9quilibre est central en cas de d\u00e9pression avec manque de motivation et \u00e9puisement \u00e9motionnel.<\/p>\n<h2>\ud83c\udf2c Les poumons - la porte du deuil<\/h2>\n<p>Selon la MTC, les poumons ne r\u00e9gulent pas seulement la respiration, mais aussi le flux du Qi dans tout le corps. Il est li\u00e9 \u00e0 l'\u00e9motion de la tristesse et \u00e0 la capacit\u00e9 de l\u00e2cher prise.<\/p>\n<p>Un Qi des poumons bloqu\u00e9 se manifeste souvent par :<\/p>\n<ul>\n<li>tristesse profonde<\/li>\n<li>Difficult\u00e9s respiratoires<\/li>\n<li>Retrait<\/li>\n<li>Sentiment de faiblesse<\/li>\n<\/ul>\n<p>Les exercices de respiration, l'acupression et les mouvements rythmiques peuvent ici aider \u00e0 faire circuler \u00e0 nouveau l'\u00e9nergie.<\/p>\n<h2>\ud83c\udf3f Le foie - ma\u00eetre du flux libre<\/h2>\n<p>Le foie assure la libre circulation du qi et des \u00e9motions. Dans la MTC, il est \u00e9troitement li\u00e9 \u00e0 la col\u00e8re, \u00e0 la frustration et \u00e0 la tension int\u00e9rieure. Si le Qi du foie stagne, cela peut entra\u00eener une agitation int\u00e9rieure, de l'irritabilit\u00e9, de la nervosit\u00e9 - ou au contraire - des troubles de l'humeur. <br>conduire \u00e0 un \u00e9puisement profond et au d\u00e9sespoir.<\/p>\n<p>Sympt\u00f4mes typiques :<\/p>\n<ul>\n<li>Irritabilit\u00e9, sautes d'humeur<\/li>\n<li>syndrome pr\u00e9menstruel, tensions, probl\u00e8mes digestifs<\/li>\n<li>humeur d\u00e9pressive avec sensation de pression dans la poitrine ou le ventre<\/li>\n<\/ul>\n<p>La stagnation du Qi du foie est l'une des racines les plus fr\u00e9quentes des troubles \u00e9motionnels en MTC.<\/p>\n<h2>\ud83c\udf72 La rate - centre de traitement et de stabilit\u00e9<\/h2>\n<p>La rate est responsable de la \"digestion\" non seulement de la nourriture, mais aussi des exp\u00e9riences v\u00e9cues. Elle te donne une stabilit\u00e9 int\u00e9rieure et une clart\u00e9 mentale.<br>Si la rate est affaiblie (souvent \u00e0 cause d'une r\u00e9flexion, de soucis, d'une position assise prolong\u00e9e ou d'une alimentation irr\u00e9guli\u00e8re), les sympt\u00f4mes sont fr\u00e9quents :<\/p>\n<ul>\n<li>Manque de motivation<\/li>\n<li>rumination permanente<\/li>\n<li>Sensation de lourdeur et de fatigue<\/li>\n<li>manque d'app\u00e9tit, fringales ou sensation de sati\u00e9t\u00e9<\/li>\n<\/ul>\n<p>Renforcer le Qi de la rate est essentiel en cas de d\u00e9pression avec \u00e9puisement et surmenage mental.<\/p>\n<h2>\ud83e\uddca Le rein - racine de la peur<\/h2>\n<p>Selon la MTC, le rein stocke notre essence vitale (Jing) et repr\u00e9sente la confiance originelle, la volont\u00e9 de vivre et la pers\u00e9v\u00e9rance. Il est directement li\u00e9 \u00e0 la peur - surtout \u00e0 l'angoisse existentielle profond\u00e9ment ancr\u00e9e ou \u00e0 l'ins\u00e9curit\u00e9 chronique.<\/p>\n<p>Une \u00e9nergie r\u00e9nale affaiblie peut se manifester par<\/p>\n<ul>\n<li>Angoisses, crises de panique<\/li>\n<li>mains et pieds froids<\/li>\n<li>Mal de dos<\/li>\n<li>troubles du sommeil (surtout en deuxi\u00e8me partie de nuit)<\/li>\n<\/ul>\n<p>Le renforcement du yang des reins (chaleur, confiance) est donc une cl\u00e9 importante en cas d'anxi\u00e9t\u00e9.<\/p>\n<h2>\ud83c\udf1e Ce que tu peux faire concr\u00e8tement - Impulsions de MTC pour le quotidien<\/h2>\n<p><strong>Le matin :<br><\/strong>-Mouvement doux (Qi Gong, yoga des m\u00e9ridiens)<br>-Petit-d\u00e9jeuner chaud avec alimentation renfor\u00e7ant la rate<br>-lumi\u00e8re consciente et respiration profonde<\/p>\n<p><strong>Au cours de la journ\u00e9e :<\/strong><br>-Fixer des objectifs petits et r\u00e9alisables<br>-Tisane de passiflore ou de m\u00e9lisse<br>-contact avec des personnes de soutien<\/p>\n<p><strong>Le soir :<\/strong><br>-rituel de gratitude<br>-bains de pieds chauds<br>-M\u00e9ditations pour renforcer le c\u0153ur ou les reins<\/p>\n<h2>\u270b L'acupressure en cas d'anxi\u00e9t\u00e9 et de d\u00e9pression - 7 points \u00e9prouv\u00e9s<\/h2>\n<p>En MTC, l'acupressure cibl\u00e9e peut aider \u00e0 \u00e9liminer les blocages \u00e9motionnels, \u00e0 r\u00e9tablir la circulation du Qi et \u00e0 stabiliser le corps et l'esprit. Tu trouveras ici sept points particuli\u00e8rement efficaces - chacun est expliqu\u00e9 en d\u00e9tail directement sur notre site :<\/p>\n<ul>\n<li><a href=\"https:\/\/www.meine-tcm.com\/fr\/points-dacupuncture\/point-dacupuncture-fo-03\/\" target=\"_blank\" rel=\"noopener\">\ud83d\udccd Le 03 - \u201eGrande r\u00e9union\u201c (T\u00e0i Ch\u014dng)<\/a><br><em>soulage les tensions \u00e9motionnelles, calme le stress et l'irritabilit\u00e9<\/em><\/li>\n<li><a href=\"https:\/\/www.meine-tcm.com\/fr\/points-dacupuncture\/point-dacupuncture-es-36\/\" target=\"_blank\" rel=\"noopener\">\ud83d\udccd Ma 36 - \u201eTrois miles de pied\u201c (Zusanli)<\/a><br><em>Renforce la rate et l'estomac, am\u00e9liore l'\u00e9nergie et l'humeur en cas de fatigue<\/em><\/li>\n<li><a href=\"https:\/\/www.meine-tcm.com\/fr\/points-dacupuncture\/point-dacupuncture-es-36\/\" target=\"_blank\" rel=\"noopener\">\ud83d\udccd<\/a><a href=\"https:\/\/www.meine-tcm.com\/fr\/points-dacupuncture\/point-dacupuncture-co-07\/\" target=\"_blank\" rel=\"noopener\"> He 07 - \"Porte de l'esprit\" (Shenmen)<\/a><br>aide en cas d'agitation, d'anxi\u00e9t\u00e9, de troubles du sommeil et d'\u00e9puisement mental<\/li>\n<li><a href=\"https:\/\/www.meine-tcm.com\/fr\/points-dacupuncture\/point-dacupuncture-vg-20\/\" target=\"_blank\" rel=\"noopener\">\ud83d\udccd LG 20 - \u201ePorte du ciel\u201c (Baihui)<\/a><br>Am\u00e9liore l'humeur et recentre, notamment en cas de vide d\u00e9pressif<\/li>\n<li><a href=\"https:\/\/www.meine-tcm.com\/fr\/points-dacupuncture\/point-dacupuncture-vc-04\/\" target=\"_blank\" rel=\"noopener\">\ud83d\udccd KG 4 - \u201ePorte du Qi d'origine\u201c (Guanyuan)<\/a><br>Renforce l'\u00e9nergie des reins, le centre int\u00e9rieur et la stabilit\u00e9 psychique<\/li>\n<li><a href=\"https:\/\/www.meine-tcm.com\/fr\/points-dacupuncture\/point-dacupuncture-vc-06\/\" target=\"_blank\" rel=\"noopener\">\ud83d\udccd KG 6 - \u201eMer du Qi\u201c (Qihai)<\/a><br>Stimule l'\u00e9nergie vitale, id\u00e9al en cas de faiblesse physique et psychique<\/li>\n<li><a href=\"https:\/\/www.meine-tcm.com\/fr\/points-dacupuncture\/point-dacupuncture-vc-12\/\" target=\"_blank\" rel=\"noopener\">\ud83d\udccd KG 12 - \u201ePoint de rassemblement de l'estomac\u201c (Zhongwan)<\/a><br>Soutient la digestion \u00e9motionnelle - en cas de rumination, de vide int\u00e9rieur et de sentiment de pl\u00e9nitude<\/li>\n<\/ul>\n<p>\ud83d\udc49 Utilisation : masser doucement pendant 1 \u00e0 2 minutes, en respirant calmement - particuli\u00e8rement efficace le matin ou le soir.<\/p>\n<p>\ud83d\udea8 Veuillez noter que l'utilisation de l'acupressure et des herbes dans le cadre de la MTC est une mesure de soutien et ne remplace pas la consultation d'un m\u00e9decin sp\u00e9cialiste ou d'un th\u00e9rapeute. En cas de sympt\u00f4mes persistants ou graves, il est important de faire appel \u00e0 une aide professionnelle.<\/p>\n<h2>\ud83e\udded Ce qui te donne en plus de la clart\u00e9 : Ton analyse MTC<\/h2>\n<p>Tu aimerais savoir quels sont tes organes qui sont actuellement d\u00e9s\u00e9quilibr\u00e9s du point de vue de la MTC ?<br><strong>Alors profite d\u00e8s maintenant de notre analyse MTC gratuite :<\/strong><br>\ud83d\udd17 <a href=\"https:\/\/www.meine-tcm.com\/fr\/analyse-tcm\/\" target=\"_blank\" rel=\"noopener\">www.meine-tcm.com\/tcm-analyse<\/a><\/p>\n<p>Tu obtiens une premi\u00e8re \u00e9valuation de ton type, des d\u00e9s\u00e9quilibres possibles et des recommandations individuelles pour ta situation - sur la base de connaissances mill\u00e9naires de la MTC.<\/p>\n<h2>\ud83d\udea8 Important : la d\u00e9pression n'est pas un signe de faiblesse<\/h2>\n<p>Dans la MTC, la tristesse est une phase de transformation - pas un \u00e9tat pour toujours.<br>Mais si tu as l'impression de ne plus pouvoir t'en sortir seul, n'h\u00e9site pas \u00e0 demander de l'aide. Un accompagnement m\u00e9dical ou th\u00e9rapeutique n'est pas en contradiction avec la MTC - mais un compl\u00e9ment pr\u00e9cieux.<\/p>\n<h2>\u2728 Conclusion<\/h2>\n<p>Selon la MTC, l'anxi\u00e9t\u00e9 et la d\u00e9pression sont dues \u00e0 des blocages \u00e9nerg\u00e9tiques, \u00e0 l'\u00e9puisement ou \u00e0 l'exc\u00e8s de certaines fonctions organiques.<br><strong>La bonne nouvelle :<\/strong> Ton syst\u00e8me est con\u00e7u pour retrouver l'\u00e9quilibre. Il te faut de la patience, de l'autocompassion - et parfois du courage,<br>accepter de l'aide.<\/p>\n<p>Car comme on dit<br><strong><em>\"La peur te retient \u00e0 la branche. Mais ton \u00eatre est fait pour le vol\".<\/em><\/strong><\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1379913981 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_581889743 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-684253659\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-684253659 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section quote\" id=\"section_1430820159\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-717190527\">\n\n\n\t<div id=\"col-1928428899\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p>Quand le c\u0153ur est triste, le monde devient gris. Mais en toi brille une lumi\u00e8re qui n'attend que de briller \u00e0 nouveau.<\/p>\n<p class=\"quote-from\">Auteur : Inconnu<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1928428899 > .col-inner {\n  max-width: 600px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1430820159 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(255, 244, 217);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-962916125\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-962916125 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section h2\" id=\"section_1668438420\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1051669410\">\n\n\n\t<div id=\"col-61024186\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Autres conseils et articles int\u00e9ressants<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-61024186 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1668438420 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section blogposts-overview\" id=\"section_403081393\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-236705246\">\n\n\n\t<div id=\"col-105970665\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n  <style>\n    #row-1218463341 .grid-col-1{height: 600px}\n    #row-1218463341 .grid-col-1-2{height: 300px}\n    #row-1218463341 .grid-col-1-3{height:200px}\n    #row-1218463341 .grid-col-2-3{height: 400px}\n    #row-1218463341 .grid-col-1-4{height: 150px}\n    #row-1218463341 .grid-col-3-4{height: 450px}\n\n\n        \/* Tablet *\/\n    @media (max-width: 850px){\n      #row-1218463341 .grid-col-1{height: 400px}\n      #row-1218463341 .grid-col-1-2{height: 200px}\n      #row-1218463341 .grid-col-1-3{height:133.33333333333px}\n      #row-1218463341 .grid-col-2-3{height: 266.66666666667px}\n      #row-1218463341 .grid-col-1-4{height: 100px}\n      #row-1218463341 .grid-col-3-4{height: 300px}\n    }\n    \n        \/* Mobile *\/\n    @media (max-width: 550px){\n      #row-1218463341 .grid-col-1{height: 400px}\n      #row-1218463341 .grid-col-1-2{height: 200px}\n      #row-1218463341 .grid-col-1-3{height:133.33333333333px}\n      #row-1218463341 .grid-col-2-3{height: 266.66666666667px}\n      #row-1218463341 .grid-col-1-4{height: 100px}\n      #row-1218463341 .grid-col-3-4{height: 300px}\n    }\n    \n\n  <\/style>\n  \n  \n    <div id=\"row-1218463341\" class=\"row row-small row-full-width row-grid\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"col post-item grid-col grid-col-1 large-6 medium-12\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/die-herz-zeit-nutzen\/\" class=\"plain\" aria-label=\"Die Herz\u2013Zeit nutzen\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/die-herz-zeit-nutzen\/\" class=\"plain\">Die Herz\u2013Zeit nutzen<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t11:47 Uhr. Du sitzt am Schreibtisch. Die Mails stapeln sich. Das Meeting vorhin war anstrengend. Du greifst zum dritten Kaffee. Oder:\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">14<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juil<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/wenn-hitze-krank-macht\/\" class=\"plain\" aria-label=\"Quand la chaleur rend malade\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Le soleil est source de vie. Mais il peut aussi \u00eatre dangereux si tu ne te prot\u00e8ges pas.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Le soleil est source de vie. Mais il peut aussi \u00eatre dangereux si tu ne te prot\u00e8ges pas.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/wenn-hitze-krank-macht\/\" class=\"plain\">Quand la chaleur rend malade<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t\u00c7a ne commence pas d'un coup. \u00c7a commence doucement. Insidieusement. On s'en rend \u00e0 peine compte. Au d\u00e9but, on est juste fatigu\u00e9. Puis on se sent alourdi. Et ensuite vient\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">07<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juil<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\" aria-label=\"Pourquoi ton ventre fait des siennes en \u00e9t\u00e9\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Le ventre sait ce que la t\u00eate ne peut pas exprimer. \u00c9coute-le.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Le ventre sait ce que la t\u00eate ne peut pas exprimer. \u00c9coute-le.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\">Pourquoi ton ventre fait des siennes en \u00e9t\u00e9<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\" aria-label=\"Pourquoi l&#039;\u00e9t\u00e9 met votre circulation \u00e0 rude \u00e9preuve \u2014 et ce que la MTC recommande pour y rem\u00e9dier\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Q\u00ed B\u00f3 | L&#039;empereur jaune Huangdi | Dr. Weber\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"S\u00e9ance photo \u00ab Demande \u00e0 l&#039;Empereur Jaune \u00bb (BTS) - juillet 2026\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tG\u00e9n\u00e9ralit\u00e9s MTC expliqu\u00e9e \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\">Pourquoi l'\u00e9t\u00e9 met votre circulation \u00e0 rude \u00e9preuve \u2014 et ce que la MTC recommande pour y rem\u00e9dier<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">26<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\" aria-label=\"La boisson estivale Yin \u2014 le secret des anciens ma\u00eetres\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"La boisson estivale Yin \u2014 le secret des anciens ma\u00eetres\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"La boisson estivale Yin \u2014 le secret des anciens ma\u00eetres\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil nutritionnel TCM de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\">La boisson estivale Yin \u2014 le secret des anciens ma\u00eetres<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">26<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/schlafprobleme-im-sommer\/\" class=\"plain\" aria-label=\"Probl\u00e8mes de sommeil en \u00e9t\u00e9\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Ce n&#039;est pas la chaleur qui t&#039;emp\u00eache de dormir. C&#039;est un fant\u00f4me qui ne peut pas trouver le repos.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Ce n&#039;est pas la chaleur qui t&#039;emp\u00eache de dormir. C&#039;est un fant\u00f4me qui ne peut pas trouver le repos.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/schlafprobleme-im-sommer\/\" class=\"plain\">Probl\u00e8mes de sommeil en \u00e9t\u00e9<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">23<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\" aria-label=\"Pourquoi vous \u00eates plus irritable en \u00e9t\u00e9 \u2014 le \u00ab feu du foie \u00bb en MTC\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Tu n&#039;es pas comme \u00e7a. Mais en ce moment, tu te sens \u00e9tranger \u00e0 toi-m\u00eame.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Tu n&#039;es pas comme \u00e7a. Mais en ce moment, tu te sens \u00e9tranger \u00e0 toi-m\u00eame.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\">Pourquoi vous \u00eates plus irritable en \u00e9t\u00e9 \u2014 le \u00ab feu du foie \u00bb en MTC<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item has-post-icon grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\" aria-label=\"RETRAITE : Qi Gong et respiration TAO (mars 2027)\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Aper\u00e7u de la retraite de qi gong au printemps au Tyrol\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t\t\t<div class=\"absolute no-click x50 y50 md-x50 md-y50 lg-x50 lg-y50\">\n  \t\t\t\t            \t<div class=\"overlay-icon\">\n  \t\t\t\t                    <i class=\"icon-play\" aria-hidden=\"true\"><\/i>  \t\t\t\t                <\/div>\n  \t\t\t\t            <\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tRetraites \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\">RETRAITE : Qi Gong et respiration TAO (mars 2027)<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">10<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-105970665 > .col-inner {\n  max-width: 1060px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_403081393 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1870732651\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1870732651 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section h2\" id=\"section_316401946\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-425788429\">\n\n\n\t<div id=\"col-1977690367\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Nos produits les plus populaires<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1977690367 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_316401946 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-902568764\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-902568764 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section top-produkte\" id=\"section_347435481\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1862893220\">\n\n\n\t<div id=\"col-1714097638\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t\n  \n    <div class=\"row  equalize-box large-columns-5 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" aria-label=\"Cours de Qi Gong pour d\u00e9butants et l\u00e9g\u00e8rement avanc\u00e9s\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-fuer-anfaenger-06-online-ansehen-mobile-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La main tient le smartphone, \u00e0 l&#039;\u00e9cran le portail de cours en ligne de Einfach besser leben.\" aria-hidden=\"true\" title=\"Cours de Qi Gong pour d\u00e9butants de Simplement mieux vivre en ligne\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Couverture image pour cours de Qi Gong pour d\u00e9butants avec Wolfgang en image\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Cours de Qi Gong pour d\u00e9butants de Simplement mieux vivre\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1368\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Cours de Qi Gong pour d\u00e9butants et l\u00e9g\u00e8rement avanc\u00e9s<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1368\" class=\"screen-reader-text\">\n\t\tCe produit a plusieurs variantes. Les options peuvent \u00eatre choisies sur la page du produit\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" aria-label=\"AkuPen - le stylo d&#039;acupuncture g\u00e9nial avec instructions vid\u00e9o\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-weiss-vertikal-3-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"AkuPen ouvert\" aria-hidden=\"true\" title=\"AkuPen de Mieux vivre, tout simplement\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"AukPen avec emballage en bois\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled-800x1131.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1087x1536.jpg 1087w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1449x2048.jpg 1449w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-8x12.jpg 8w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled.jpg 1811w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"AkuPen avec instructions vid\u00e9o\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1365\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tAkuPen\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">AkuPen - le stylo d'acupuncture g\u00e9nial avec instructions vid\u00e9o<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>80,57&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1365\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" aria-label=\"Cours de Qi Gong II - Les 18 figures de l&#039;harmonie\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-05-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La main tient le smartphone, \u00e0 l&#039;\u00e9cran le portail de cours en ligne de Einfach besser leben.\" aria-hidden=\"true\" title=\"Cours vid\u00e9o en ligne de Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Image de couverture pour le cours de Qi Qong moderne - Les 18 figures de l&#039;harmonie\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Cours de Qi Qong - Les 18 figures de l&#039;harmonie\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1376\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Cours de Qi Gong II - Les 18 figures de l'harmonie<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>35,19&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1376\" class=\"screen-reader-text\">\n\t\tCe produit a plusieurs variantes. Les options peuvent \u00eatre choisies sur la page du produit\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-kurs-8-brokate\/\" aria-label=\"Les 8 brocards - Le cours de qi gong moderne I\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/qi-gong-kurs-8-brokate-07-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La main tient le smartphone, \u00e0 l&#039;\u00e9cran le portail de cours en ligne de Einfach besser leben.\" aria-hidden=\"true\" title=\"Cours vid\u00e9o en ligne de Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Couverture Image du cours de Qi Gong moderne 8 brocards avec Wolfgang\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-800x1130.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-600x847.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i.jpg 1062w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Le cours de Qi Gong moderne 8 brocards de Vivre mieux, tout simplement\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1416\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-kurs-8-brokate\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Les 8 brocards - Le cours de qi gong moderne I<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1416\" class=\"screen-reader-text\">\n\t\tCe produit a plusieurs variantes. Les options peuvent \u00eatre choisies sur la page du produit\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/weidinger-w08-warme-mitte\/\" aria-label=\"Weidinger W08 - Centre chaud\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-1-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"M\u00e9lange d&#039;herbes MTC W08 - Centre chaud du Dr Weidinger\" aria-hidden=\"true\" title=\"M\u00e9lange d&#039;herbes MTC W08 - Centre chaud du Dr Weidinger\" \/><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"M\u00e9lange d&#039;herbes MTC W08 - Centre chaud du Dr Weidinger\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"M\u00e9lange d&#039;herbes MTC W08 - Centre chaud du Dr Weidinger\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1295\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tHerbes de MTC\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/weidinger-w08-warme-mitte\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Weidinger W08 - Centre chaud<\/a><\/p><p class=\"woocommerce-loop-product__subtitle wp-subtitle\">TCM m\u00e9lange d'herbes<\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>62,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1295\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1714097638 > .col-inner {\n  max-width: 1200px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_347435481 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n<style>\nh2 {\ntext-align: left;\n}\n\nsection.one-image .img {\nmargin-bottom: 0 !important;\n}\n\nsection.one-image img {\n    border-radius: 15px;\n}\n<\/style>\n\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>de la peur. La tristesse. Le vide int\u00e9rieur.<br \/>\nPour de nombreuses personnes, ces sentiments ne sont pas une phase \u00e0 court terme, mais un \u00e9tat permanent p\u00e9nible. En m\u00e9decine traditionnelle chinoise (MTC), on ne consid\u00e8re pas ces \u00e9tats \u00e9motionnels comme des probl\u00e8mes psychiques isol\u00e9s, mais comme l'expression d'un flux \u00e9nerg\u00e9tique perturb\u00e9 dans le corps - en particulier dans les circuits fonctionnels du c\u0153ur, du foie, de la rate, des reins et des poumons.<\/p>","protected":false},"author":3859,"featured_media":19054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[300],"tags":[],"class_list":["post-19052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tcm-tipp-der-woche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Angst &amp; Depressionen: Hilfe aus der TCM mit Akupressur<\/title>\n<meta name=\"description\" content=\"Was tun bei Angst und Depression? Erfahre, wie TCM und Akupressur gezielt Herz, Leber und Milz st\u00e4rken \u2014 mit Tipps, Punkten &amp; kostenloser TCM\u2013Analyse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meine-tcm.com\/fr\/anxiete-et-depression-du-point-de-vue-de-la-tcm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angst &amp; Depressionen: Hilfe aus der TCM mit Akupressur\" \/>\n<meta property=\"og:description\" content=\"Was tun bei Angst und Depression? Erfahre, wie TCM und Akupressur gezielt Herz, Leber und Milz st\u00e4rken \u2014 mit Tipps, Punkten &amp; kostenloser TCM\u2013Analyse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meine-tcm.com\/fr\/anxiete-et-depression-du-point-de-vue-de-la-tcm\/\" \/>\n<meta property=\"og:site_name\" content=\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-18T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"2160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/\"},\"author\":{\"name\":\"Marina\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/76da350caed5aad1d9998ba607d86f28\"},\"headline\":\"Angst und Depressionen aus Sicht der TCM\",\"datePublished\":\"2025-06-18T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/\"},\"wordCount\":1313,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/angst-depressionen.jpg\",\"articleSection\":[\"TCM Tipp der Woche\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/\",\"name\":\"Angst & Depressionen: Hilfe aus der TCM mit Akupressur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/angst-depressionen.jpg\",\"datePublished\":\"2025-06-18T05:00:00+00:00\",\"description\":\"Was tun bei Angst und Depression? Erfahre, wie TCM und Akupressur gezielt Herz, Leber und Milz st\u00e4rken \u2014 mit Tipps, Punkten & kostenloser TCM\u2013Analyse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/angst-depressionen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/angst-depressionen.jpg\",\"width\":2160,\"height\":2160,\"caption\":\"Die Angst h\u00e4lt dich am Zweig. Doch dein Wesen ist gemacht f\u00fcr den Flug.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/angst-und-depressionen-aus-sicht-der-tcm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meine-tcm.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angst und Depressionen aus Sicht der TCM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"name\":\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\",\"description\":\"Einfach gesund bleiben\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meine-tcm.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\",\"name\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"width\":559,\"height\":479,\"caption\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/meinetcm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EinfachbesserLeben\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/76da350caed5aad1d9998ba607d86f28\",\"name\":\"Marina\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anxi\u00e9t\u00e9 et d\u00e9pression : L'aide de la MTC avec l'acupressure","description":"Que faire en cas d'anxi\u00e9t\u00e9 et de d\u00e9pression ? D\u00e9couvrez comment la MTC et l'acupressure renforcent de mani\u00e8re cibl\u00e9e le c\u0153ur, le foie et la rate - avec des conseils, des points &amp; une analyse MTC gratuite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meine-tcm.com\/fr\/anxiete-et-depression-du-point-de-vue-de-la-tcm\/","og_locale":"fr_FR","og_type":"article","og_title":"Angst & Depressionen: Hilfe aus der TCM mit Akupressur","og_description":"Was tun bei Angst und Depression? Erfahre, wie TCM und Akupressur gezielt Herz, Leber und Milz st\u00e4rken \u2014 mit Tipps, Punkten & kostenloser TCM\u2013Analyse.","og_url":"https:\/\/www.meine-tcm.com\/fr\/anxiete-et-depression-du-point-de-vue-de-la-tcm\/","og_site_name":"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt","article_published_time":"2025-06-18T05:00:00+00:00","og_image":[{"width":2160,"height":2160,"url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen.jpg","type":"image\/jpeg"}],"author":"Marina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marina","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/#article","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/"},"author":{"name":"Marina","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/76da350caed5aad1d9998ba607d86f28"},"headline":"Angst und Depressionen aus Sicht der TCM","datePublished":"2025-06-18T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/"},"wordCount":1313,"commentCount":0,"publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"image":{"@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen.jpg","articleSection":["TCM Tipp der Woche"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/","url":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/","name":"Anxi\u00e9t\u00e9 et d\u00e9pression : L'aide de la MTC avec l'acupressure","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/#primaryimage"},"image":{"@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen.jpg","datePublished":"2025-06-18T05:00:00+00:00","description":"Que faire en cas d'anxi\u00e9t\u00e9 et de d\u00e9pression ? D\u00e9couvrez comment la MTC et l'acupressure renforcent de mani\u00e8re cibl\u00e9e le c\u0153ur, le foie et la rate - avec des conseils, des points &amp; une analyse MTC gratuite.","breadcrumb":{"@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/#primaryimage","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen.jpg","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/06\/angst-depressionen.jpg","width":2160,"height":2160,"caption":"Die Angst h\u00e4lt dich am Zweig. Doch dein Wesen ist gemacht f\u00fcr den Flug."},{"@type":"BreadcrumbList","@id":"https:\/\/www.meine-tcm.com\/angst-und-depressionen-aus-sicht-der-tcm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meine-tcm.com\/"},{"@type":"ListItem","position":2,"name":"Angst und Depressionen aus Sicht der TCM"}]},{"@type":"WebSite","@id":"https:\/\/www.meine-tcm.com\/#website","url":"https:\/\/www.meine-tcm.com\/","name":"meine MTC | La m\u00e9decine traditionnelle chinoise expliqu\u00e9e simplement","description":"Rester en bonne sant\u00e9, tout simplement","publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meine-tcm.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.meine-tcm.com\/#organization","name":"mon-TCM.com - La m\u00e9decine traditionnelle chinoise expliqu\u00e9e simplement","url":"https:\/\/www.meine-tcm.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","width":559,"height":479,"caption":"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt"},"image":{"@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/meinetcm\/","https:\/\/www.youtube.com\/@EinfachbesserLeben"]},{"@type":"Person","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/76da350caed5aad1d9998ba607d86f28","name":"Marina"}]}},"wps_subtitle":"Wenn die Seele leidet \u2014 was dein Herz, deine Leber und deine Milz damit zu tun haben","_links":{"self":[{"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/posts\/19052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/users\/3859"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/comments?post=19052"}],"version-history":[{"count":0,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/posts\/19052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/media\/19054"}],"wp:attachment":[{"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/media?parent=19052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/categories?post=19052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/tags?post=19052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}