{"id":18817,"date":"2025-05-14T07:00:00","date_gmt":"2025-05-14T05:00:00","guid":{"rendered":"https:\/\/www.meine-tcm.com\/?p=18817"},"modified":"2025-05-05T11:40:03","modified_gmt":"2025-05-05T09:40:03","slug":"sautes-dhumeur-manque-dentrain-agitation-interieure","status":"publish","type":"post","link":"https:\/\/www.meine-tcm.com\/fr\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/","title":{"rendered":"Sautes d'humeur, manque de motivation, agitation int\u00e9rieure ?"},"content":{"rendered":"<section class=\"section main-teaser\" id=\"section_742440901\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-202655560\">\n\n\n\t<div id=\"col-275853672\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"teaser\">Tu te sens souvent fatigu\u00e9(e), irritable ou agit\u00e9(e) int\u00e9rieurement.<br \/>Et tu ne sais pas vraiment pourquoi ?<br \/>Tu as peut-\u00eatre d\u00e9j\u00e0 essay\u00e9 de mieux dormir, de faire plus d'exercice ou de trier tes pens\u00e9es - mais les baisses de moral persistent malgr\u00e9 tout ?<br \/>Une cl\u00e9 souvent n\u00e9glig\u00e9e se trouve dans ton ventre : ton axe intestin-cerveau.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-275853672 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_742440901 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1562411544\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1562411544 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section one-image\" id=\"section_1336595410\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-929512004\">\n\n\n\t<div id=\"col-1462771467\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_758430949\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"2160\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2.jpg\" class=\"attachment-original size-original\" alt=\"Ton ventre participe \u00e0 la r\u00e9flexion. Ton humeur commence dans ton intestin.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2.jpg 2160w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2-12x12.jpg 12w\" sizes=\"auto, (max-width: 2160px) 100vw, 2160px\" title=\"Ton ventre participe \u00e0 la r\u00e9flexion. Ton humeur commence dans ton intestin.\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_758430949 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p class=\"caption\">Ton ventre participe \u00e0 la r\u00e9flexion. Ton humeur commence dans ton intestin.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1462771467 > .col-inner {\n  border-radius: 10px;\n  max-width: 640px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1336595410 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-423866347\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-423866347 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section text\" id=\"section_1010353779\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1641756360\">\n\n\n\t<div id=\"col-1370158635\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n<h2>\ud83e\udde0 Ton ventre pense avec toi - et ressent avec toi<\/h2>\n<p>Il existe un lien direct entre ton intestin et ton cerveau :<br \/>l'axe intestin-cerveau. Pr\u00e8s de 90 % de s\u00e9rotonine, l'hormone du bonheur<br \/>ne se forment pas dans la t\u00eate, mais dans le syst\u00e8me digestif.<\/p>\n<p>Si ta flore intestinale est d\u00e9s\u00e9quilibr\u00e9e, tu le sentiras tr\u00e8s vite :<\/p>\n<ul>\n<li>Baisse de moral<\/li>\n<li>agitation int\u00e9rieure<\/li>\n<li>mauvais sommeil<\/li>\n<li>augmentation des r\u00e9actions de stress<\/li>\n<\/ul>\n<p>Peut-\u00eatre connais-tu ce \"sentiment de malaise\" dans l'estomac ?<br \/>Ce n'est pas un hasard.<\/p>\n<h2>\ud83d\udca1 intuition = biologie<\/h2>\n<p>Ton intestin parle \u00e0 ton cerveau - via le nerf vague.<br \/>Et ce, plus rapidement que tu ne peux le penser consciemment.<\/p>\n<p>Des \u00e9tudes r\u00e9centes montrent que : La communication de l'intestin au cerveau<br \/>se d\u00e9roule en quelques millisecondes. Ton intuition est donc de la vraie biochimie, pas de l'imagination.<\/p>\n<h2>\ud83c\udf3e Ce dont ton intestin a besoin : Fibres alimentaires<\/h2>\n<p>Les fibres alimentaires sont la nourriture pr\u00e9f\u00e9r\u00e9e de tes bact\u00e9ries intestinales b\u00e9n\u00e9fiques.<br \/>Ils favorisent la formation d'acides gras \u00e0 cha\u00eene courte comme le butyrate, qui :<br \/><br \/>\u2705 R\u00e9duire l'inflammation de l'intestin<br \/>\u2705 renforcer la muqueuse intestinale<br \/>\u2705 soutenir la production d'hormones du bonheur<\/p>\n<p>Ce que tu manges contribue donc chaque jour \u00e0 d\u00e9terminer ton \u00e9quilibre \u00e9motionnel.<\/p>\n<h2>Nourriture pour ton syst\u00e8me nerveux<\/h2>\n<p>Un autre effet passionnant :<br \/>Les fibres alimentaires augmentent la production de BDNF (Brain Derived Neurotrophic Factor) - un facteur de croissance pour ton cerveau.<\/p>\n<p><strong>BDNF<\/strong> soutenu :<\/p>\n<ul>\n<li>la connexion entre les cellules nerveuses<\/li>\n<li>stabilit\u00e9 \u00e9motionnelle<\/li>\n<li>ta r\u00e9sistance au stress<\/li>\n<\/ul>\n<p>En d'autres termes :<br \/>Un intestin sain envoie des signaux de renforcement \u00e0 ton cerveau - tous les jours.<\/p>\n<h2>\ud83e\udd66 5 aides riches en fibres pour ton humeur<\/h2>\n<ol>\n<li><strong>Ecorces de psyllium<\/strong> - riches en fibres solubles, apaisent les intestins et aident \u00e0 lutter contre les sympt\u00f4mes du c\u00f4lon irritable.<\/li>\n<li><strong>Flocons d'avoine<\/strong> - fournissent des b\u00eata-glucanes qui ont un effet anti-inflammatoire et maintiennent la courbe de glyc\u00e9mie stable.<\/li>\n<li><strong>Artichauts<\/strong> - sont particuli\u00e8rement riches en inuline, une fibre pr\u00e9biotique qui nourrit tes bonnes bact\u00e9ries intestinales.<\/li>\n<li><strong>Brocoli<\/strong> - contient des fibres et des substances v\u00e9g\u00e9tales secondaires qui favorisent ta flore intestinale et inhibent les inflammations.<\/li>\n<li><strong>Baies<\/strong> (p. ex. myrtilles, framboises) - apportent non seulement des fibres, mais aussi des polyph\u00e9nols antioxydants pour soutenir ta sant\u00e9 cellulaire.<\/li>\n<\/ol>\n<h2><strong>\ud83c\udf7d Fibres alimentaires : ton tampon naturel contre le stress<\/strong><\/h2>\n<p><strong>Des \u00e9tudes montrent<\/strong><br \/>Les personnes qui mangent richement en fibres ont souvent des taux de cortisol plus bas -<br \/>donc moins de l'hormone de stress produite par le corps.<\/p>\n<p>\u2192 Plus de calme dans le corps = plus de calme int\u00e9rieur au quotidien.<\/p>\n<p>\ud83d\udc49 <strong>Important :<\/strong> Introduis lentement les nouvelles fibres et bois suffisamment d'eau pour que ton intestin puisse bien s'adapter.<\/p>\n<h2>\ud83c\udf3f Si tu veux faire vraiment du bien \u00e0 ton intestin<\/h2>\n<p>Ce n'est pas tous les jours que l'on parvient \u00e0 int\u00e9grer suffisamment de brocolis, de baies ou de flocons d'avoine dans son quotidien.<br \/>C'est justement \u00e0 ce moment-l\u00e0 que BS+ Fibres Plus peut \u00eatre un soutien pr\u00e9cieux.<\/p>\n<p>Cette formule naturelle combine<\/p>\n<ul>\n<li><strong>fibres solubles<\/strong> en fibres d'acacia et en amidon r\u00e9sistant<\/li>\n<li><strong>Polyph\u00e9nols<\/strong> \u00e0 base de baies, de l\u00e9gumes et d'extraits de plantes<\/li>\n<li><strong>D-Tagatose<\/strong>un type de sucre particulier ayant un effet pr\u00e9biotique<\/li>\n<\/ul>\n<p>\u27a1\ufe0f En savoir plus sur BS+ : <a href=\"https:\/\/www.meine-tcm.com\/fr\/produit\/bs-fibres-alimentaires-plus\/\" target=\"_blank\" rel=\"noopener\">www.meine-tcm.com\/produkt\/bs-ballaststoffe-plus<\/a><\/p>\n<h2>\u2728 Conclusion :<\/h2>\n<p>Ton humeur commence dans ton ventre.<br \/>En prenant soin de ta sant\u00e9 intestinale, tu renforces automatiquement ta t\u00eate et ton c\u0153ur.<\/p>\n<p>Petits changements - grands effets.<br \/>Tu n'as pas besoin d'\u00eatre parfait. Mais tu peux commencer d\u00e8s aujourd'hui.<\/p>\n<h2>\ud83c\udf1f Ton plan en 3 \u00e9tapes pour plus de bien-\u00eatre :<\/h2>\n<ol>\n<li>Commence aujourd'hui par un petit-d\u00e9jeuner riche en fibres (par exemple, des flocons d'avoine avec des baies).<\/li>\n<li>Bois 2 \u00e0 2,5 litres d'eau par jour pour soutenir ta flore intestinale.<\/li>\n<li>Compl\u00e8te de mani\u00e8re cibl\u00e9e si n\u00e9cessaire - par exemple avec Fibres alimentaires BS+ Plus pour assurer ta bonne base.<\/li>\n<\/ol>\n<p>\u2728 Petits changements - grands effets.<br \/>Ton ventre et ta t\u00eate t'en remercieront.<\/p>\n<h2>\ud83e\udd63 Happy-Darm Overnight Oats<\/h2>\n<ul>\n<li><strong>Ingr\u00e9dients :<\/strong><br \/>- 3 cuill\u00e8res \u00e0 soupe de flocons d'avoine (tendres ou \u00e0 p\u00e9pins)<br \/>- 1 cuill\u00e8re \u00e0 soupe d'enveloppe de psyllium<br \/>- 1 cuill\u00e8re \u00e0 caf\u00e9 de graines de lin (enti\u00e8res ou concass\u00e9es)<br \/>- 150-200 ml d'eau (alternative : lait d'avoine ou d'amande possible)<\/li>\n<li><strong>Le matin, ajouter des produits frais :<br \/><\/strong>- 1 poign\u00e9e de baies fra\u00eeches ou surgel\u00e9es (p. ex. myrtilles, framboises)<br \/>- 2-3 cs de yaourt ou d'alternative v\u00e9g\u00e9tale<br \/>- 1 cuill\u00e8re \u00e0 caf\u00e9 d'huile de lin<br \/>- 1 pinc\u00e9e de curcuma (facultatif, pour un effet anti-inflammatoire)<br \/>- un peu de cannelle ou de vanille en poudre (facultatif)<\/li>\n<li><strong>Pr\u00e9paration :<br \/><\/strong>- Le soir : mettre les flocons d'avoine, le t\u00e9gument de psyllium et les graines de lin dans un verre.<br \/>ou dans un bol.<br \/>- Verser de l'eau (ou du lait v\u00e9g\u00e9tal) et bien m\u00e9langer.<br \/>- Laisser gonfler toute la nuit au r\u00e9frig\u00e9rateur - au moins 6 heures.<br \/>- Le matin : ajouter les baies, le yaourt, l'huile de lin, le curcuma et la cannelle\/vanille fra\u00eechement m\u00e9lang\u00e9s et d\u00e9guster.<\/li>\n<\/ul>\n<p>\u2728 Cette recette est riche en fibres, anti-inflammatoire et soutient ton axe intestin-cerveau de mani\u00e8re naturelle - parfaite pour plus de l\u00e9g\u00e8ret\u00e9 et d'\u00e9quilibre \u00e9motionnel.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1370158635 > .col-inner {\n  max-width: 800px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1010353779 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-626789184\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-626789184 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section quote\" id=\"section_915755013\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-176517813\">\n\n\n\t<div id=\"col-103108863\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<p>L'harmonie na\u00eet lorsque nous respectons la sagesse de notre corps et que nous vivons avec ses rythmes naturels.<\/p>\n<p class=\"quote-from\">Auteur : Inconnu<\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-103108863 > .col-inner {\n  max-width: 600px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_915755013 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(255, 244, 217);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1812418277\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1812418277 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section h2\" id=\"section_2038687584\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-953942633\">\n\n\n\t<div id=\"col-1220157669\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Autres conseils et articles int\u00e9ressants<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1220157669 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2038687584 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section blogposts-overview\" id=\"section_1390465430\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1897493641\">\n\n\n\t<div id=\"col-649883711\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n  <style>\n    #row-1118023991 .grid-col-1{height: 600px}\n    #row-1118023991 .grid-col-1-2{height: 300px}\n    #row-1118023991 .grid-col-1-3{height:200px}\n    #row-1118023991 .grid-col-2-3{height: 400px}\n    #row-1118023991 .grid-col-1-4{height: 150px}\n    #row-1118023991 .grid-col-3-4{height: 450px}\n\n\n        \/* Tablet *\/\n    @media (max-width: 850px){\n      #row-1118023991 .grid-col-1{height: 400px}\n      #row-1118023991 .grid-col-1-2{height: 200px}\n      #row-1118023991 .grid-col-1-3{height:133.33333333333px}\n      #row-1118023991 .grid-col-2-3{height: 266.66666666667px}\n      #row-1118023991 .grid-col-1-4{height: 100px}\n      #row-1118023991 .grid-col-3-4{height: 300px}\n    }\n    \n        \/* Mobile *\/\n    @media (max-width: 550px){\n      #row-1118023991 .grid-col-1{height: 400px}\n      #row-1118023991 .grid-col-1-2{height: 200px}\n      #row-1118023991 .grid-col-1-3{height:133.33333333333px}\n      #row-1118023991 .grid-col-2-3{height: 266.66666666667px}\n      #row-1118023991 .grid-col-1-4{height: 100px}\n      #row-1118023991 .grid-col-3-4{height: 300px}\n    }\n    \n\n  <\/style>\n  \n  \n    <div id=\"row-1118023991\" class=\"row row-small row-full-width row-grid\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"col post-item grid-col grid-col-1 large-6 medium-12\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/die-herz-zeit-nutzen\/\" class=\"plain\" aria-label=\"Die Herz\u2013Zeit nutzen\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-3-herz-zeit-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Dein Herz hat jeden Tag seine Stunde. Verpasst du sie, merkt es das.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/die-herz-zeit-nutzen\/\" class=\"plain\">Die Herz\u2013Zeit nutzen<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t11:47 Uhr. Du sitzt am Schreibtisch. Die Mails stapeln sich. Das Meeting vorhin war anstrengend. Du greifst zum dritten Kaffee. Oder:\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">14<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juil<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/wenn-hitze-krank-macht\/\" class=\"plain\" aria-label=\"Quand la chaleur rend malade\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Le soleil est source de vie. Mais il peut aussi \u00eatre dangereux si tu ne te prot\u00e8ges pas.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juli-Beitrag-1-hitze-tcm-12x12.jpg 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"Le soleil est source de vie. Mais il peut aussi \u00eatre dangereux si tu ne te prot\u00e8ges pas.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/wenn-hitze-krank-macht\/\" class=\"plain\">Quand la chaleur rend malade<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t\u00c7a ne commence pas d'un coup. \u00c7a commence doucement. Insidieusement. On s'en rend \u00e0 peine compte. Au d\u00e9but, on est juste fatigu\u00e9. Puis on se sent alourdi. Et ensuite vient\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">07<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juil<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\" aria-label=\"Pourquoi ton ventre fait des siennes en \u00e9t\u00e9\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Le ventre sait ce que la t\u00eate ne peut pas exprimer. \u00c9coute-le.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-5-verdauung-im-sommer-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Le ventre sait ce que la t\u00eate ne peut pas exprimer. \u00c9coute-le.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/warum-dein-bauch-im-sommer-rebelliert\/\" class=\"plain\">Pourquoi ton ventre fait des siennes en \u00e9t\u00e9<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\" aria-label=\"Pourquoi l&#039;\u00e9t\u00e9 met votre circulation \u00e0 rude \u00e9preuve \u2014 et ce que la MTC recommande pour y rem\u00e9dier\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Q\u00ed B\u00f3 | L&#039;empereur jaune Huangdi | Dr. Weber\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/3weisen-gespraech-sommerhitze-bts-1066x800-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"S\u00e9ance photo \u00ab Demande \u00e0 l&#039;Empereur Jaune \u00bb (BTS) - juillet 2026\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tG\u00e9n\u00e9ralit\u00e9s MTC expliqu\u00e9e \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/sommerhitze-kreislauf-yin-schuetzen\/\" class=\"plain\">Pourquoi l'\u00e9t\u00e9 met votre circulation \u00e0 rude \u00e9preuve \u2014 et ce que la MTC recommande pour y rem\u00e9dier<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">26<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\" aria-label=\"La boisson estivale Yin \u2014 le secret des anciens ma\u00eetres\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"La boisson estivale Yin \u2014 le secret des anciens ma\u00eetres\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/yin-sommer-drink-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"La boisson estivale Yin \u2014 le secret des anciens ma\u00eetres\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil nutritionnel TCM de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/wassermelone-minze-yin-sommer-drink\/\" class=\"plain\">La boisson estivale Yin \u2014 le secret des anciens ma\u00eetres<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">26<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/schlafprobleme-im-sommer\/\" class=\"plain\" aria-label=\"Probl\u00e8mes de sommeil en \u00e9t\u00e9\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Ce n&#039;est pas la chaleur qui t&#039;emp\u00eache de dormir. C&#039;est un fant\u00f4me qui ne peut pas trouver le repos.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-3-schlafstoerungen-shen-unruhe-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Ce n&#039;est pas la chaleur qui t&#039;emp\u00eache de dormir. C&#039;est un fant\u00f4me qui ne peut pas trouver le repos.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/schlafprobleme-im-sommer\/\" class=\"plain\">Probl\u00e8mes de sommeil en \u00e9t\u00e9<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">23<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\" aria-label=\"Pourquoi vous \u00eates plus irritable en \u00e9t\u00e9 \u2014 le \u00ab feu du foie \u00bb en MTC\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Tu n&#039;es pas comme \u00e7a. Mais en ce moment, tu te sens \u00e9tranger \u00e0 toi-m\u00eame.\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-1536x1536.jpg 1536w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-2048x2048.jpg 2048w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/03\/juni-Beitrag-4-reizbarkeit-leber-feuer-12x12.jpg 12w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Tu n&#039;es pas comme \u00e7a. Mais en ce moment, tu te sens \u00e9tranger \u00e0 toi-m\u00eame.\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tConseil MTC de la semaine \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/sommer-gereiztheit-leber-feuer\/\" class=\"plain\">Pourquoi vous \u00eates plus irritable en \u00e9t\u00e9 \u2014 le \u00ab feu du foie \u00bb en MTC<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item has-post-icon grid-col grid-col-1-2 large-3 medium-6\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-default box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\" aria-label=\"RETRAITE : Qi Gong et respiration TAO (mars 2027)\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"280\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-280x280.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2026\/06\/qi-gong-retreat-im-freuhling-in-tirol-preview-100x100.jpg 100w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" title=\"Aper\u00e7u de la retraite de qi gong au printemps au Tyrol\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t\t\t<div class=\"absolute no-click x50 y50 md-x50 md-y50 lg-x50 lg-y50\">\n  \t\t\t\t            \t<div class=\"overlay-icon\">\n  \t\t\t\t                    <i class=\"icon-play\" aria-hidden=\"true\"><\/i>  \t\t\t\t                <\/div>\n  \t\t\t\t            <\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label  is-xxsmall op-7 uppercase\">\n\t\t\t\t\tRetraites \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/retreat-qi-gong-tao-breathwork-maerz-2027\/\" class=\"plain\">RETRAITE : Qi Gong et respiration TAO (mars 2027)<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">10<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Juin<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-649883711 > .col-inner {\n  max-width: 1060px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1390465430 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-2010725743\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2010725743 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section h2\" id=\"section_308768975\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-975057183\">\n\n\n\t<div id=\"col-254677349\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Nos produits les plus populaires<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-254677349 > .col-inner {\n  max-width: 960px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_308768975 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-729575956\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-729575956 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section top-produkte\" id=\"section_1554255381\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-center\"  id=\"row-1401392789\">\n\n\n\t<div id=\"col-1868747776\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t\n  \n    <div class=\"row  equalize-box large-columns-5 medium-columns-3 small-columns-2 row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" aria-label=\"Cours de Qi Gong pour d\u00e9butants et l\u00e9g\u00e8rement avanc\u00e9s\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-fuer-anfaenger-06-online-ansehen-mobile-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La main tient le smartphone, \u00e0 l&#039;\u00e9cran le portail de cours en ligne de Einfach besser leben.\" aria-hidden=\"true\" title=\"Cours de Qi Gong pour d\u00e9butants de Simplement mieux vivre en ligne\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Couverture image pour cours de Qi Gong pour d\u00e9butants avec Wolfgang en image\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/1cover-qi-gong-fuer-anfaenger.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Cours de Qi Gong pour d\u00e9butants de Simplement mieux vivre\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1368\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-fuer-anfaenger-und-leicht-fortgeschrittene\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Cours de Qi Gong pour d\u00e9butants et l\u00e9g\u00e8rement avanc\u00e9s<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1368\" class=\"screen-reader-text\">\n\t\tCe produit a plusieurs variantes. Les options peuvent \u00eatre choisies sur la page du produit\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" aria-label=\"AkuPen - le stylo d&#039;acupuncture g\u00e9nial avec instructions vid\u00e9o\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-weiss-vertikal-3-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"AkuPen ouvert\" aria-hidden=\"true\" title=\"AkuPen de Mieux vivre, tout simplement\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"AukPen avec emballage en bois\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled-800x1131.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1087x1536.jpg 1087w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-1449x2048.jpg 1449w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-8x12.jpg 8w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/Akupen-mit-Verpackung-auf-weiss-2400x3392-1-scaled.jpg 1811w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"AkuPen avec instructions vid\u00e9o\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1365\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tAkuPen\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/akupen-der-geniale-akupunkturstift-mit-videoanleitung\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">AkuPen - le stylo d'acupuncture g\u00e9nial avec instructions vid\u00e9o<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>80,57&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1365\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" aria-label=\"Cours de Qi Gong II - Les 18 figures de l&#039;harmonie\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-05-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La main tient le smartphone, \u00e0 l&#039;\u00e9cran le portail de cours en ligne de Einfach besser leben.\" aria-hidden=\"true\" title=\"Cours vid\u00e9o en ligne de Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Image de couverture pour le cours de Qi Qong moderne - Les 18 figures de l&#039;harmonie\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-510x721.jpg 510w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01-600x848.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/08\/qi-gong-kurs-18-figuren-der-harmonie-01.jpg 764w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Cours de Qi Qong - Les 18 figures de l&#039;harmonie\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1376\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-kurs-18-figuren-der-harmonie\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Cours de Qi Gong II - Les 18 figures de l'harmonie<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>35,19&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1376\" class=\"screen-reader-text\">\n\t\tCe produit a plusieurs variantes. Les options peuvent \u00eatre choisies sur la page du produit\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-kurs-8-brokate\/\" aria-label=\"Les 8 brocards - Le cours de qi gong moderne I\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/qi-gong-kurs-8-brokate-07-smartphone-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"La main tient le smartphone, \u00e0 l&#039;\u00e9cran le portail de cours en ligne de Einfach besser leben.\" aria-hidden=\"true\" title=\"Cours vid\u00e9o en ligne de Einfach besser leben\" \/><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg\" class=\"attachment-medium size-medium\" alt=\"Couverture Image du cours de Qi Gong moderne 8 brocards avec Wolfgang\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-283x400.jpg 283w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-800x1130.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-566x800.jpg 566w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-768x1085.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i-600x847.jpg 600w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2014\/06\/1qi-gong-i.jpg 1062w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" title=\"Le cours de Qi Gong moderne 8 brocards de Vivre mieux, tout simplement\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1416\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tQi Gong\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/qi-gong-kurs-8-brokate\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Les 8 brocards - Le cours de qi gong moderne I<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>25,11&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1416\" class=\"screen-reader-text\">\n\t\tCe produit a plusieurs variantes. Les options peuvent \u00eatre choisies sur la page du produit\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-zoom\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/weidinger-w08-warme-mitte\/\" aria-label=\"Weidinger W08 - Centre chaud\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"480\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-1-400x480.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"M\u00e9lange d&#039;herbes MTC W08 - Centre chaud du Dr Weidinger\" aria-hidden=\"true\" title=\"M\u00e9lange d&#039;herbes MTC W08 - Centre chaud du Dr Weidinger\" \/><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg\" class=\"attachment-medium size-medium\" alt=\"M\u00e9lange d&#039;herbes MTC W08 - Centre chaud du Dr Weidinger\" srcset=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-400x400.jpg 400w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-100x100.jpg 100w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-800x800.jpg 800w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-280x280.jpg 280w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-768x768.jpg 768w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten-12x12.jpg 12w, https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2024\/04\/weidinger-w08-warme-mitte-240-tabletten.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" title=\"M\u00e9lange d&#039;herbes MTC W08 - Centre chaud du Dr Weidinger\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"1295\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Aper\u00e7u<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tWeidinger\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/www.meine-tcm.com\/fr\/produkt\/weidinger-w08-warme-mitte\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Weidinger W08 - Centre chaud<\/a><\/p><p class=\"woocommerce-loop-product__subtitle wp-subtitle\">TCM m\u00e9lange d'herbes<\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>62,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">\u20ac<\/span><\/bdi><\/span><\/span>\n\n\n<\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_1295\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1868747776 > .col-inner {\n  max-width: 1200px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1554255381 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n<style>\nh2 {\ntext-align: left;\n}\n\nsection.one-image .img {\nmargin-bottom: 0 !important;\n}\n\nsection.one-image img {\n    border-radius: 15px;\n}\n<\/style>","protected":false},"excerpt":{"rendered":"<p>Tu te sens souvent fatigu\u00e9(e), irritable ou agit\u00e9(e) int\u00e9rieurement - et tu ne sais pas exactement pourquoi ?<br \/>\nTu as peut-\u00eatre d\u00e9j\u00e0 essay\u00e9 de mieux dormir, de faire plus d'exercice ou de trier tes pens\u00e9es - mais les baisses de moral persistent malgr\u00e9 tout ?<\/p>","protected":false},"author":3859,"featured_media":18819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[300],"tags":[],"class_list":["post-18817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tcm-tipp-der-woche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie dein Darm deine Gesundheit und Stimmung beeinflusst<\/title>\n<meta name=\"description\" content=\"Die Darm\u2013Hirn\u2013Achse spielt eine zentrale Rolle f\u00fcr dein emotionales Gleichgewicht, deine Nervenst\u00e4rke und dein Immunsystem \u2014 jeden Tag.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meine-tcm.com\/fr\/sautes-dhumeur-manque-dentrain-agitation-interieure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie dein Darm deine Gesundheit und Stimmung beeinflusst\" \/>\n<meta property=\"og:description\" content=\"Die Darm\u2013Hirn\u2013Achse spielt eine zentrale Rolle f\u00fcr dein emotionales Gleichgewicht, deine Nervenst\u00e4rke und dein Immunsystem \u2014 jeden Tag.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meine-tcm.com\/fr\/sautes-dhumeur-manque-dentrain-agitation-interieure\/\" \/>\n<meta property=\"og:site_name\" content=\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-14T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"2160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/\"},\"author\":{\"name\":\"Marina\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/76da350caed5aad1d9998ba607d86f28\"},\"headline\":\"Stimmungsschwankungen, Antriebslosigkeit, innere Unruhe?\",\"datePublished\":\"2025-05-14T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/\"},\"wordCount\":1018,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/bauch-stimmung-beitrag-2.jpg\",\"articleSection\":[\"TCM Tipp der Woche\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/\",\"name\":\"Wie dein Darm deine Gesundheit und Stimmung beeinflusst\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/bauch-stimmung-beitrag-2.jpg\",\"datePublished\":\"2025-05-14T05:00:00+00:00\",\"description\":\"Die Darm\u2013Hirn\u2013Achse spielt eine zentrale Rolle f\u00fcr dein emotionales Gleichgewicht, deine Nervenst\u00e4rke und dein Immunsystem \u2014 jeden Tag.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/bauch-stimmung-beitrag-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/bauch-stimmung-beitrag-2.jpg\",\"width\":2160,\"height\":2160,\"caption\":\"Dein Bauch denkt mit. Deine Stimmung beginnt im Darm.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meine-tcm.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stimmungsschwankungen, Antriebslosigkeit, innere Unruhe?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#website\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"name\":\"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt\",\"description\":\"Einfach gesund bleiben\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meine-tcm.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#organization\",\"name\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"contentUrl\":\"https:\\\/\\\/www.meine-tcm.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png\",\"width\":559,\"height\":479,\"caption\":\"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/meinetcm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@EinfachbesserLeben\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.meine-tcm.com\\\/#\\\/schema\\\/person\\\/76da350caed5aad1d9998ba607d86f28\",\"name\":\"Marina\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment tes intestins influencent ta sant\u00e9 et ton humeur","description":"L'axe intestin-cerveau joue un r\u00f4le central dans ton \u00e9quilibre \u00e9motionnel, ta force nerveuse et ton syst\u00e8me immunitaire - chaque jour.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meine-tcm.com\/fr\/sautes-dhumeur-manque-dentrain-agitation-interieure\/","og_locale":"fr_FR","og_type":"article","og_title":"Wie dein Darm deine Gesundheit und Stimmung beeinflusst","og_description":"Die Darm\u2013Hirn\u2013Achse spielt eine zentrale Rolle f\u00fcr dein emotionales Gleichgewicht, deine Nervenst\u00e4rke und dein Immunsystem \u2014 jeden Tag.","og_url":"https:\/\/www.meine-tcm.com\/fr\/sautes-dhumeur-manque-dentrain-agitation-interieure\/","og_site_name":"meine TCM | Traditionelle Chinesische Medizin einfach erkl\u00e4rt","article_published_time":"2025-05-14T05:00:00+00:00","og_image":[{"width":2160,"height":2160,"url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2.jpg","type":"image\/jpeg"}],"author":"Marina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marina","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/#article","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/"},"author":{"name":"Marina","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/76da350caed5aad1d9998ba607d86f28"},"headline":"Stimmungsschwankungen, Antriebslosigkeit, innere Unruhe?","datePublished":"2025-05-14T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/"},"wordCount":1018,"commentCount":0,"publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"image":{"@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2.jpg","articleSection":["TCM Tipp der Woche"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/","url":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/","name":"Comment tes intestins influencent ta sant\u00e9 et ton humeur","isPartOf":{"@id":"https:\/\/www.meine-tcm.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/#primaryimage"},"image":{"@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2.jpg","datePublished":"2025-05-14T05:00:00+00:00","description":"L'axe intestin-cerveau joue un r\u00f4le central dans ton \u00e9quilibre \u00e9motionnel, ta force nerveuse et ton syst\u00e8me immunitaire - chaque jour.","breadcrumb":{"@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/#primaryimage","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2.jpg","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2025\/04\/bauch-stimmung-beitrag-2.jpg","width":2160,"height":2160,"caption":"Dein Bauch denkt mit. Deine Stimmung beginnt im Darm."},{"@type":"BreadcrumbList","@id":"https:\/\/www.meine-tcm.com\/stimmungsschwankungen-antriebslosigkeit-innere-unruhe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meine-tcm.com\/"},{"@type":"ListItem","position":2,"name":"Stimmungsschwankungen, Antriebslosigkeit, innere Unruhe?"}]},{"@type":"WebSite","@id":"https:\/\/www.meine-tcm.com\/#website","url":"https:\/\/www.meine-tcm.com\/","name":"meine MTC | La m\u00e9decine traditionnelle chinoise expliqu\u00e9e simplement","description":"Rester en bonne sant\u00e9, tout simplement","publisher":{"@id":"https:\/\/www.meine-tcm.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meine-tcm.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.meine-tcm.com\/#organization","name":"mon-TCM.com - La m\u00e9decine traditionnelle chinoise expliqu\u00e9e simplement","url":"https:\/\/www.meine-tcm.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","contentUrl":"https:\/\/www.meine-tcm.com\/wp-content\/uploads\/2022\/08\/meine-tcm-traditionelle-chinesische-medizin-einfach-erklaert.png","width":559,"height":479,"caption":"meine-TCM.com \u2014 Traditionelle chinesische Medizin einfach erkl\u00e4rt"},"image":{"@id":"https:\/\/www.meine-tcm.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/meinetcm\/","https:\/\/www.youtube.com\/@EinfachbesserLeben"]},{"@type":"Person","@id":"https:\/\/www.meine-tcm.com\/#\/schema\/person\/76da350caed5aad1d9998ba607d86f28","name":"Marina"}]}},"wps_subtitle":"Dein Darm k\u00f6nnte der Grund sein.","_links":{"self":[{"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/posts\/18817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/users\/3859"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/comments?post=18817"}],"version-history":[{"count":0,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/posts\/18817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/media\/18819"}],"wp:attachment":[{"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/media?parent=18817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/categories?post=18817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.meine-tcm.com\/fr\/wp-json\/wp\/v2\/tags?post=18817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}